{"id":1830,"date":"2013-07-31T18:54:41","date_gmt":"2013-07-31T18:54:41","guid":{"rendered":"http:\/\/utel.mx\/blog\/?p=1830"},"modified":"2023-03-10T16:52:52","modified_gmt":"2023-03-10T16:52:52","slug":"mba-en-mexico","status":"publish","type":"post","link":"https:\/\/utel.mx\/blog\/business-school\/mba-en-mexico\/","title":{"rendered":"MBA en M\u00e9xico"},"content":{"rendered":"<p style=\"text-align: left;\" align=\"center\">MBA\u00a0 (Master in Business Administration), mejor conocido como Master en Administraci\u00f3n de Negocios, es un programa acad\u00e9mico a nivel de posgrado en la especializaci\u00f3n de actividades comerciales.<\/p>\n<p>Las universidades que maneja este programa acad\u00e9mico se interesan en el desarrollo de las actividades extraescolares, servicios comunitarios y en la contribuci\u00f3n futura del estudiante al desarrollo social, a trav\u00e9s de su capacidad de liderazgo y desempe\u00f1o profesional.<\/p>\n<p>Para ingresar a un Master en Administraci\u00f3n de Negocios, se requiere de una serie de caracter\u00edsticas, tales como: experiencia profesional en el campo,\u00a0 contar con cartas de recomendaci\u00f3n y mostrar seguridad en las entrevistas de car\u00e1cter personal.<\/p>\n<p>MBA basa su estructura en conocimientos sobre econom\u00eda, organizaci\u00f3n, marketing, contabilidad, finanzas, gesti\u00f3n empresarial, negocios internacionales, gesti\u00f3n de empresas en tecnolog\u00eda de la informaci\u00f3n, uso efectivo de los recursos humanos y estrategias pol\u00edticas.<\/p>\n<p>Nuevos sistemas de estudio, como las universidades en l\u00ednea, ofrecen atractivos planes de carrera en donde pueden visualizarse interesantes estrategias profesionales enfocadas a los negocios; alternativas de desarrollo laboral para j\u00f3venes y ejecutivos emprendedores que buscan ampliar sus conocimientos y\u00a0 oportunidades econ\u00f3micas.<\/p>\n<p>Actualmente la oferta de programas MBA se encuentran en aumento, ya que prometen una exitosa formaci\u00f3n profesional y beneficiosas remuneraciones econ\u00f3micas.<\/p>\n<p>En M\u00e9xico MBA se especializa y se concentra en el desarrollo de habilidades corporativas que permiten cumplir con los retos que exigen puestos de alto rango,\u00a0 a trav\u00e9s de la aplicaci\u00f3n de modelos vanguardistas.<\/p>\n<p>Ante ello, el portal \u201cGu\u00eda de posgrados\u201d se\u00f1ala que estudiar un Master en Administraci\u00f3n de Negocios\u00a0 v\u00eda internet es una buena opci\u00f3n para aquellos que buscan generar conocimientos s\u00f3lidos y mejorar su nivel de vida. Adem\u00e1s de considerar que la inversi\u00f3n durante el estudio de la carrera oscila entre los 28 mil y los 45 mil d\u00f3lares, para posteriormente, como egresado, recibir un sueldo promedio que va desde los 150 mil d\u00f3lares, cantidad que tiene probabilidad de multiplicarse una vez liberado el t\u00edtulo.<\/p>\n<p>Concretar la idea de iniciar una carrera de negocios v\u00eda online, es una opci\u00f3n a considerar. Realizar una especializaci\u00f3n que econ\u00f3micamente supere cualquier pretensi\u00f3n de salario, es encontrarse con nuevos caminos que entrelacen el conocimiento y crecimiento\u00a0 profesional.<\/p>\n<p>La <a href=\"http:\/\/posgrados.utel.edu.mx\/interes\/administracion-de-negocios-en-linea\/\">Maestr\u00eda en l\u00ednea en Administraci\u00f3n de Negocios<\/a> de\u00a0la Universidad UTEL,\u00a0\u00a0facilita la adquisici\u00f3n de habilidades esenciales para la toma de decisiones dentro de las empresas y otorga una formaci\u00f3n integral en la Planeaci\u00f3n, Organizaci\u00f3n, Direcci\u00f3n y Control de procesos, ejecutivos y operativos, de las diferentes \u00e1reas de las organizaciones.<\/p>\n<p><b>Mar\u00eda M\u00e9ndez Coronel<\/b><br \/>\n<b>UTEL Editorial<\/b><\/p>\n<div id=\"advads-104623170\" class=\"advads-cta-lp-banner-form advads-entity-placement\"><a href=\"https:\/\/utel.mx\/blog\/admisiones-universidad-online\/?utm_source=blog&#038;utm_medium=CTAlink&#038;utm_campaign=MKTseo\" aria-label=\"Universidad en linea\"><img src=\"https:\/\/utel.mx\/blog\/wp-content\/uploads\/2025\/04\/universidad-en-linea-1.png\" alt=\"Universidad en linea\"  srcset=\"https:\/\/utel.mx\/blog\/wp-content\/uploads\/2025\/04\/universidad-en-linea-1.png 626w, https:\/\/utel.mx\/blog\/wp-content\/uploads\/2025\/04\/universidad-en-linea-1-420x168.png 420w\" sizes=\"(max-width: 626px) 100vw, 626px\" width=\"626\" height=\"250\"   \/><\/a><\/div>","protected":false},"excerpt":{"rendered":"<p> [&hellip;]<\/p>\n","protected":false},"author":40,"featured_media":3738,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-gradient":""}},"footnotes":""},"categories":[3461],"tags":[],"class_list":["post-1830","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-business-school"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>MBA en M\u00e9xico - BLOG | Utel<\/title>\n<meta name=\"description\" content=\"Nuevos sistemas de estudio, ofrecen planes de carrera donde pueden visualizarse estrategias profesionales enfocadas a los MBA. Aprende m\u00e1s aqu\u00ed\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/utel.mx\/blog\/business-school\/mba-en-mexico\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"MBA en M\u00e9xico - BLOG | Utel\" \/>\n<meta property=\"og:description\" content=\"Nuevos sistemas de estudio, ofrecen planes de carrera donde pueden visualizarse estrategias profesionales enfocadas a los MBA. Aprende m\u00e1s aqu\u00ed\" \/>\n<meta property=\"og:url\" content=\"https:\/\/utel.mx\/blog\/business-school\/mba-en-mexico\/\" \/>\n<meta property=\"og:site_name\" content=\"BLOG | Utel\" \/>\n<meta property=\"article:published_time\" content=\"2013-07-31T18:54:41+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-03-10T16:52:52+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/utel.mx\/blog\/wp-content\/uploads\/2013\/08\/shutterstock_117648712.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"667\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Invitados UTEL\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Invitados UTEL\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/utel.mx\/blog\/business-school\/mba-en-mexico\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/utel.mx\/blog\/business-school\/mba-en-mexico\/\"},\"author\":{\"name\":\"Invitados UTEL\",\"@id\":\"https:\/\/utel.mx\/blog\/#\/schema\/person\/e5b3d8d918f13bd0b0f4724daa90dd95\"},\"headline\":\"MBA en M\u00e9xico\",\"datePublished\":\"2013-07-31T18:54:41+00:00\",\"dateModified\":\"2023-03-10T16:52:52+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/utel.mx\/blog\/business-school\/mba-en-mexico\/\"},\"wordCount\":462,\"publisher\":{\"@id\":\"https:\/\/utel.mx\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/utel.mx\/blog\/business-school\/mba-en-mexico\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/utel.mx\/blog\/wp-content\/uploads\/2013\/08\/shutterstock_117648712.jpg\",\"articleSection\":[\"Business School\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/utel.mx\/blog\/business-school\/mba-en-mexico\/\",\"url\":\"https:\/\/utel.mx\/blog\/business-school\/mba-en-mexico\/\",\"name\":\"MBA en M\u00e9xico - BLOG | Utel\",\"isPartOf\":{\"@id\":\"https:\/\/utel.mx\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/utel.mx\/blog\/business-school\/mba-en-mexico\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/utel.mx\/blog\/business-school\/mba-en-mexico\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/utel.mx\/blog\/wp-content\/uploads\/2013\/08\/shutterstock_117648712.jpg\",\"datePublished\":\"2013-07-31T18:54:41+00:00\",\"dateModified\":\"2023-03-10T16:52:52+00:00\",\"description\":\"Nuevos sistemas de estudio, ofrecen planes de carrera donde pueden visualizarse estrategias profesionales enfocadas a los MBA. Aprende m\u00e1s aqu\u00ed\",\"breadcrumb\":{\"@id\":\"https:\/\/utel.mx\/blog\/business-school\/mba-en-mexico\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/utel.mx\/blog\/business-school\/mba-en-mexico\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/utel.mx\/blog\/business-school\/mba-en-mexico\/#primaryimage\",\"url\":\"https:\/\/utel.mx\/blog\/wp-content\/uploads\/2013\/08\/shutterstock_117648712.jpg\",\"contentUrl\":\"https:\/\/utel.mx\/blog\/wp-content\/uploads\/2013\/08\/shutterstock_117648712.jpg\",\"width\":1000,\"height\":667,\"caption\":\"MBA en M\u00e9xico | Blog - UTEL\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/utel.mx\/blog\/business-school\/mba-en-mexico\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/utel.mx\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"MBA en M\u00e9xico\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/utel.mx\/blog\/#website\",\"url\":\"https:\/\/utel.mx\/blog\/\",\"name\":\"BLOG | Utel\",\"description\":\"Blog UTEL Universidad en L\u00ednea\",\"publisher\":{\"@id\":\"https:\/\/utel.mx\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/utel.mx\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/utel.mx\/blog\/#organization\",\"name\":\"BLOG | Utel\",\"url\":\"https:\/\/utel.mx\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/utel.mx\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/utel.mx\/blog\/wp-content\/uploads\/2023\/03\/cropped-logo-blog.png\",\"contentUrl\":\"https:\/\/utel.mx\/blog\/wp-content\/uploads\/2023\/03\/cropped-logo-blog.png\",\"width\":237,\"height\":64,\"caption\":\"BLOG | Utel\"},\"image\":{\"@id\":\"https:\/\/utel.mx\/blog\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/utel.mx\/blog\/#\/schema\/person\/e5b3d8d918f13bd0b0f4724daa90dd95\",\"name\":\"Invitados UTEL\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/utel.mx\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/781456f1128be5a332ab27ea8b902597?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/781456f1128be5a332ab27ea8b902597?s=96&d=mm&r=g\",\"caption\":\"Invitados UTEL\"},\"description\":\"Invitados . Colaboraciones por parte de invitados de la Comunidad UTEL\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"MBA en M\u00e9xico - BLOG | Utel","description":"Nuevos sistemas de estudio, ofrecen planes de carrera donde pueden visualizarse estrategias profesionales enfocadas a los MBA. Aprende m\u00e1s aqu\u00ed","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/utel.mx\/blog\/business-school\/mba-en-mexico\/","og_locale":"es_ES","og_type":"article","og_title":"MBA en M\u00e9xico - BLOG | Utel","og_description":"Nuevos sistemas de estudio, ofrecen planes de carrera donde pueden visualizarse estrategias profesionales enfocadas a los MBA. Aprende m\u00e1s aqu\u00ed","og_url":"https:\/\/utel.mx\/blog\/business-school\/mba-en-mexico\/","og_site_name":"BLOG | Utel","article_published_time":"2013-07-31T18:54:41+00:00","article_modified_time":"2023-03-10T16:52:52+00:00","og_image":[{"width":1000,"height":667,"url":"https:\/\/utel.mx\/blog\/wp-content\/uploads\/2013\/08\/shutterstock_117648712.jpg","type":"image\/jpeg"}],"author":"Invitados UTEL","twitter_misc":{"Written by":"Invitados UTEL","Est. reading time":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/utel.mx\/blog\/business-school\/mba-en-mexico\/#article","isPartOf":{"@id":"https:\/\/utel.mx\/blog\/business-school\/mba-en-mexico\/"},"author":{"name":"Invitados UTEL","@id":"https:\/\/utel.mx\/blog\/#\/schema\/person\/e5b3d8d918f13bd0b0f4724daa90dd95"},"headline":"MBA en M\u00e9xico","datePublished":"2013-07-31T18:54:41+00:00","dateModified":"2023-03-10T16:52:52+00:00","mainEntityOfPage":{"@id":"https:\/\/utel.mx\/blog\/business-school\/mba-en-mexico\/"},"wordCount":462,"publisher":{"@id":"https:\/\/utel.mx\/blog\/#organization"},"image":{"@id":"https:\/\/utel.mx\/blog\/business-school\/mba-en-mexico\/#primaryimage"},"thumbnailUrl":"https:\/\/utel.mx\/blog\/wp-content\/uploads\/2013\/08\/shutterstock_117648712.jpg","articleSection":["Business School"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/utel.mx\/blog\/business-school\/mba-en-mexico\/","url":"https:\/\/utel.mx\/blog\/business-school\/mba-en-mexico\/","name":"MBA en M\u00e9xico - BLOG | Utel","isPartOf":{"@id":"https:\/\/utel.mx\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/utel.mx\/blog\/business-school\/mba-en-mexico\/#primaryimage"},"image":{"@id":"https:\/\/utel.mx\/blog\/business-school\/mba-en-mexico\/#primaryimage"},"thumbnailUrl":"https:\/\/utel.mx\/blog\/wp-content\/uploads\/2013\/08\/shutterstock_117648712.jpg","datePublished":"2013-07-31T18:54:41+00:00","dateModified":"2023-03-10T16:52:52+00:00","description":"Nuevos sistemas de estudio, ofrecen planes de carrera donde pueden visualizarse estrategias profesionales enfocadas a los MBA. Aprende m\u00e1s aqu\u00ed","breadcrumb":{"@id":"https:\/\/utel.mx\/blog\/business-school\/mba-en-mexico\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/utel.mx\/blog\/business-school\/mba-en-mexico\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/utel.mx\/blog\/business-school\/mba-en-mexico\/#primaryimage","url":"https:\/\/utel.mx\/blog\/wp-content\/uploads\/2013\/08\/shutterstock_117648712.jpg","contentUrl":"https:\/\/utel.mx\/blog\/wp-content\/uploads\/2013\/08\/shutterstock_117648712.jpg","width":1000,"height":667,"caption":"MBA en M\u00e9xico | Blog - UTEL"},{"@type":"BreadcrumbList","@id":"https:\/\/utel.mx\/blog\/business-school\/mba-en-mexico\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/utel.mx\/blog\/"},{"@type":"ListItem","position":2,"name":"MBA en M\u00e9xico"}]},{"@type":"WebSite","@id":"https:\/\/utel.mx\/blog\/#website","url":"https:\/\/utel.mx\/blog\/","name":"BLOG | Utel","description":"Blog UTEL Universidad en L\u00ednea","publisher":{"@id":"https:\/\/utel.mx\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/utel.mx\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/utel.mx\/blog\/#organization","name":"BLOG | Utel","url":"https:\/\/utel.mx\/blog\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/utel.mx\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/utel.mx\/blog\/wp-content\/uploads\/2023\/03\/cropped-logo-blog.png","contentUrl":"https:\/\/utel.mx\/blog\/wp-content\/uploads\/2023\/03\/cropped-logo-blog.png","width":237,"height":64,"caption":"BLOG | Utel"},"image":{"@id":"https:\/\/utel.mx\/blog\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/utel.mx\/blog\/#\/schema\/person\/e5b3d8d918f13bd0b0f4724daa90dd95","name":"Invitados UTEL","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/utel.mx\/blog\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/781456f1128be5a332ab27ea8b902597?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/781456f1128be5a332ab27ea8b902597?s=96&d=mm&r=g","caption":"Invitados UTEL"},"description":"Invitados . Colaboraciones por parte de invitados de la Comunidad UTEL"}]}},"_links":{"self":[{"href":"https:\/\/utel.mx\/blog\/wp-json\/wp\/v2\/posts\/1830","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/utel.mx\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/utel.mx\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/utel.mx\/blog\/wp-json\/wp\/v2\/users\/40"}],"replies":[{"embeddable":true,"href":"https:\/\/utel.mx\/blog\/wp-json\/wp\/v2\/comments?post=1830"}],"version-history":[{"count":1,"href":"https:\/\/utel.mx\/blog\/wp-json\/wp\/v2\/posts\/1830\/revisions"}],"predecessor-version":[{"id":44780,"href":"https:\/\/utel.mx\/blog\/wp-json\/wp\/v2\/posts\/1830\/revisions\/44780"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/utel.mx\/blog\/wp-json\/wp\/v2\/media\/3738"}],"wp:attachment":[{"href":"https:\/\/utel.mx\/blog\/wp-json\/wp\/v2\/media?parent=1830"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/utel.mx\/blog\/wp-json\/wp\/v2\/categories?post=1830"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/utel.mx\/blog\/wp-json\/wp\/v2\/tags?post=1830"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}