{"id":2183,"date":"2013-09-09T20:34:46","date_gmt":"2013-09-09T20:34:46","guid":{"rendered":"http:\/\/utel.mx\/blog\/?p=2183"},"modified":"2023-03-10T16:55:07","modified_gmt":"2023-03-10T16:55:07","slug":"glass-la-nueva-tecnologia-de-google","status":"publish","type":"post","link":"https:\/\/utel.mx\/blog\/dia-a-dia\/glass-la-nueva-tecnologia-de-google\/","title":{"rendered":"Glass, la nueva tecnolog\u00eda de Google"},"content":{"rendered":"<p>El a\u00f1o pasado, Google present\u00f3 su nuevo producto \u201cGoogle Glass\u201d en el congreso para desarrolladores que se celebra todos los a\u00f1os en San Francisco.<\/p>\n<p>Project glass es un programa de investigaci\u00f3n y desarrollo con el fin de crear unas gafas de realidad aumentada; el prop\u00f3sito de esta nueva tecnolog\u00eda es mostrar informaci\u00f3n disponible sin utilizar las manos, permitiendo el acceso a Internet mediante \u00f3rdenes de voz.<\/p>\n<p>El dise\u00f1o de Google Glass ha ido evolucionando desde su presentaci\u00f3n, siendo cada vez m\u00e1s ligeros; estos lentes cuentan con una pantalla de 640 x 360 a menos de un cent\u00edmetro del ojo; detr\u00e1s de la oreja se aloja el CPU y la bater\u00eda, en la sien se encuentra el men\u00fa t\u00e1ctil que permite ser controlado con pocos gestos; cuenta con una c\u00e1mara de 5 MP y grabaci\u00f3n de video a 720p con una memoria de 16 GB, conexi\u00f3n WiFi y Bluetooth, adem\u00e1s de altavoz tiene un micr\u00f3fono integrado para el reconocimiento de voz.<\/p>\n<p>Aunque la venta al p\u00fablico ser\u00e1 hasta el pr\u00f3ximo a\u00f1o, muy pocas personas han tenido acceso al instrumento y \u00a0entre los afortunados se encuentran \u00a0expertos en tecnolog\u00eda, creando aplicaciones para las nuevas gafas y algunos voluntarios que las prueban, debido al estricto secreto con el que se maneja esta tecnolog\u00eda, sobre todo por miedo a que otra empresa pueda copiarla y comercializarla.<\/p>\n<p>Pero realmente \u00bfQu\u00e9 son las Gafas de Goolge? Se dice que en el futuro pueden reemplazar a los tel\u00e9fonos inteligentes, siendo un nuevo dispositivo incorporado a nuestro organismo capaz de ser manipulado con solo comandos de voz; aunque se habla de que su precio no ser\u00e1 el de un producto de lujo, si tendr\u00e1 un costo elevado.<\/p>\n<p>El sistema de reconocimiento es sorprendente, aunque hasta la fecha solo est\u00e1 disponible en ingl\u00e9s, pero con solo decir el comando \u201cOK Glass\u201d se activa el sistema para despu\u00e9s decir los comandos de la funci\u00f3n que se requiera, con frases como \u201cTake a picture\u201d (toma una fotograf\u00eda) o \u201crecord a video\u201d (Graba un video) entre otras funciones, como compartir im\u00e1genes, mandar mensajes, buscar alguna ubicaci\u00f3n, etc.<\/p>\n<p>El reconocimiento de voz funciona a\u00fan en un lugar con ruido, no tiene problema en reconocer cada palabra a la perfecci\u00f3n; esto gracias a la parte\u00a0 donde se almacena la bater\u00eda, el cual tiene un sistema que detecta las vibraciones de voz mediante la cabeza.<\/p>\n<p>Pero ser\u00e1 hasta el pr\u00f3ximo a\u00f1o que se den m\u00e1s especificaciones sobre este nuevo gadget, puesto que las funciones y aplicaciones que tiene son muy pocas, poniendo a trabajar intensamente a los\u00a0desarrolladores para aprovechar al m\u00e1ximo esta nueva tecnolog\u00eda.<\/p>\n<p><b>Iv\u00e1n Mendoza<\/b><\/p>\n<p><b><\/b><b>UTEL Editorial<\/b><\/p>\n<div id=\"advads-609159508\" class=\"advads-cta-lp-banner-form advads-entity-placement\"><a href=\"https:\/\/utel.mx\/blog\/admisiones-universidad-online\/?utm_source=blog&#038;utm_medium=CTAlink&#038;utm_campaign=MKTseo\" aria-label=\"Universidad en linea\"><img src=\"https:\/\/utel.mx\/blog\/wp-content\/uploads\/2025\/04\/universidad-en-linea-1.png\" alt=\"Universidad en linea\"  srcset=\"https:\/\/utel.mx\/blog\/wp-content\/uploads\/2025\/04\/universidad-en-linea-1.png 626w, https:\/\/utel.mx\/blog\/wp-content\/uploads\/2025\/04\/universidad-en-linea-1-420x168.png 420w\" sizes=\"(max-width: 626px) 100vw, 626px\" width=\"626\" height=\"250\"   \/><\/a><\/div>","protected":false},"excerpt":{"rendered":"<p> [&hellip;]<\/p>\n","protected":false},"author":40,"featured_media":2188,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-gradient":""}},"footnotes":""},"categories":[3163],"tags":[],"class_list":["post-2183","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-dia-a-dia"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Glass, la nueva tecnolog\u00eda de Google - BLOG | Utel<\/title>\n<meta name=\"description\" content=\"El avance tecnol\u00f3gico de Google no se queda solo en la pantalla y planea desplazar a los smartphones. Conoce que es lo que est\u00e1 planeando.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/utel.mx\/blog\/dia-a-dia\/glass-la-nueva-tecnologia-de-google\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Glass, la nueva tecnolog\u00eda de Google - BLOG | Utel\" \/>\n<meta property=\"og:description\" content=\"El avance tecnol\u00f3gico de Google no se queda solo en la pantalla y planea desplazar a los smartphones. Conoce que es lo que est\u00e1 planeando.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/utel.mx\/blog\/dia-a-dia\/glass-la-nueva-tecnologia-de-google\/\" \/>\n<meta property=\"og:site_name\" content=\"BLOG | Utel\" \/>\n<meta property=\"article:published_time\" content=\"2013-09-09T20:34:46+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-03-10T16:55:07+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/utel.mx\/blog\/wp-content\/uploads\/2013\/06\/shutterstock_140433580.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2700\" \/>\n\t<meta property=\"og:image:height\" content=\"1800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Invitados UTEL\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Invitados UTEL\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/utel.mx\/blog\/dia-a-dia\/glass-la-nueva-tecnologia-de-google\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/utel.mx\/blog\/dia-a-dia\/glass-la-nueva-tecnologia-de-google\/\"},\"author\":{\"name\":\"Invitados UTEL\",\"@id\":\"https:\/\/utel.mx\/blog\/#\/schema\/person\/e5b3d8d918f13bd0b0f4724daa90dd95\"},\"headline\":\"Glass, la nueva tecnolog\u00eda de Google\",\"datePublished\":\"2013-09-09T20:34:46+00:00\",\"dateModified\":\"2023-03-10T16:55:07+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/utel.mx\/blog\/dia-a-dia\/glass-la-nueva-tecnologia-de-google\/\"},\"wordCount\":476,\"publisher\":{\"@id\":\"https:\/\/utel.mx\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/utel.mx\/blog\/dia-a-dia\/glass-la-nueva-tecnologia-de-google\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/utel.mx\/blog\/wp-content\/uploads\/2013\/06\/shutterstock_140433580.jpg\",\"articleSection\":[\"D\u00eda a d\u00eda\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/utel.mx\/blog\/dia-a-dia\/glass-la-nueva-tecnologia-de-google\/\",\"url\":\"https:\/\/utel.mx\/blog\/dia-a-dia\/glass-la-nueva-tecnologia-de-google\/\",\"name\":\"Glass, la nueva tecnolog\u00eda de Google - BLOG | Utel\",\"isPartOf\":{\"@id\":\"https:\/\/utel.mx\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/utel.mx\/blog\/dia-a-dia\/glass-la-nueva-tecnologia-de-google\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/utel.mx\/blog\/dia-a-dia\/glass-la-nueva-tecnologia-de-google\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/utel.mx\/blog\/wp-content\/uploads\/2013\/06\/shutterstock_140433580.jpg\",\"datePublished\":\"2013-09-09T20:34:46+00:00\",\"dateModified\":\"2023-03-10T16:55:07+00:00\",\"description\":\"El avance tecnol\u00f3gico de Google no se queda solo en la pantalla y planea desplazar a los smartphones. Conoce que es lo que est\u00e1 planeando.\",\"breadcrumb\":{\"@id\":\"https:\/\/utel.mx\/blog\/dia-a-dia\/glass-la-nueva-tecnologia-de-google\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/utel.mx\/blog\/dia-a-dia\/glass-la-nueva-tecnologia-de-google\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/utel.mx\/blog\/dia-a-dia\/glass-la-nueva-tecnologia-de-google\/#primaryimage\",\"url\":\"https:\/\/utel.mx\/blog\/wp-content\/uploads\/2013\/06\/shutterstock_140433580.jpg\",\"contentUrl\":\"https:\/\/utel.mx\/blog\/wp-content\/uploads\/2013\/06\/shutterstock_140433580.jpg\",\"width\":2700,\"height\":1800},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/utel.mx\/blog\/dia-a-dia\/glass-la-nueva-tecnologia-de-google\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/utel.mx\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Glass, la nueva tecnolog\u00eda de Google\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/utel.mx\/blog\/#website\",\"url\":\"https:\/\/utel.mx\/blog\/\",\"name\":\"BLOG | Utel\",\"description\":\"Blog UTEL Universidad en L\u00ednea\",\"publisher\":{\"@id\":\"https:\/\/utel.mx\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/utel.mx\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/utel.mx\/blog\/#organization\",\"name\":\"BLOG | Utel\",\"url\":\"https:\/\/utel.mx\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/utel.mx\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/utel.mx\/blog\/wp-content\/uploads\/2023\/03\/cropped-logo-blog.png\",\"contentUrl\":\"https:\/\/utel.mx\/blog\/wp-content\/uploads\/2023\/03\/cropped-logo-blog.png\",\"width\":237,\"height\":64,\"caption\":\"BLOG | Utel\"},\"image\":{\"@id\":\"https:\/\/utel.mx\/blog\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/utel.mx\/blog\/#\/schema\/person\/e5b3d8d918f13bd0b0f4724daa90dd95\",\"name\":\"Invitados UTEL\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/utel.mx\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/781456f1128be5a332ab27ea8b902597?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/781456f1128be5a332ab27ea8b902597?s=96&d=mm&r=g\",\"caption\":\"Invitados UTEL\"},\"description\":\"Invitados . Colaboraciones por parte de invitados de la Comunidad UTEL\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Glass, la nueva tecnolog\u00eda de Google - BLOG | Utel","description":"El avance tecnol\u00f3gico de Google no se queda solo en la pantalla y planea desplazar a los smartphones. Conoce que es lo que est\u00e1 planeando.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/utel.mx\/blog\/dia-a-dia\/glass-la-nueva-tecnologia-de-google\/","og_locale":"es_ES","og_type":"article","og_title":"Glass, la nueva tecnolog\u00eda de Google - BLOG | Utel","og_description":"El avance tecnol\u00f3gico de Google no se queda solo en la pantalla y planea desplazar a los smartphones. Conoce que es lo que est\u00e1 planeando.","og_url":"https:\/\/utel.mx\/blog\/dia-a-dia\/glass-la-nueva-tecnologia-de-google\/","og_site_name":"BLOG | Utel","article_published_time":"2013-09-09T20:34:46+00:00","article_modified_time":"2023-03-10T16:55:07+00:00","og_image":[{"width":2700,"height":1800,"url":"https:\/\/utel.mx\/blog\/wp-content\/uploads\/2013\/06\/shutterstock_140433580.jpg","type":"image\/jpeg"}],"author":"Invitados UTEL","twitter_misc":{"Written by":"Invitados UTEL","Est. reading time":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/utel.mx\/blog\/dia-a-dia\/glass-la-nueva-tecnologia-de-google\/#article","isPartOf":{"@id":"https:\/\/utel.mx\/blog\/dia-a-dia\/glass-la-nueva-tecnologia-de-google\/"},"author":{"name":"Invitados UTEL","@id":"https:\/\/utel.mx\/blog\/#\/schema\/person\/e5b3d8d918f13bd0b0f4724daa90dd95"},"headline":"Glass, la nueva tecnolog\u00eda de Google","datePublished":"2013-09-09T20:34:46+00:00","dateModified":"2023-03-10T16:55:07+00:00","mainEntityOfPage":{"@id":"https:\/\/utel.mx\/blog\/dia-a-dia\/glass-la-nueva-tecnologia-de-google\/"},"wordCount":476,"publisher":{"@id":"https:\/\/utel.mx\/blog\/#organization"},"image":{"@id":"https:\/\/utel.mx\/blog\/dia-a-dia\/glass-la-nueva-tecnologia-de-google\/#primaryimage"},"thumbnailUrl":"https:\/\/utel.mx\/blog\/wp-content\/uploads\/2013\/06\/shutterstock_140433580.jpg","articleSection":["D\u00eda a d\u00eda"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/utel.mx\/blog\/dia-a-dia\/glass-la-nueva-tecnologia-de-google\/","url":"https:\/\/utel.mx\/blog\/dia-a-dia\/glass-la-nueva-tecnologia-de-google\/","name":"Glass, la nueva tecnolog\u00eda de Google - BLOG | Utel","isPartOf":{"@id":"https:\/\/utel.mx\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/utel.mx\/blog\/dia-a-dia\/glass-la-nueva-tecnologia-de-google\/#primaryimage"},"image":{"@id":"https:\/\/utel.mx\/blog\/dia-a-dia\/glass-la-nueva-tecnologia-de-google\/#primaryimage"},"thumbnailUrl":"https:\/\/utel.mx\/blog\/wp-content\/uploads\/2013\/06\/shutterstock_140433580.jpg","datePublished":"2013-09-09T20:34:46+00:00","dateModified":"2023-03-10T16:55:07+00:00","description":"El avance tecnol\u00f3gico de Google no se queda solo en la pantalla y planea desplazar a los smartphones. Conoce que es lo que est\u00e1 planeando.","breadcrumb":{"@id":"https:\/\/utel.mx\/blog\/dia-a-dia\/glass-la-nueva-tecnologia-de-google\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/utel.mx\/blog\/dia-a-dia\/glass-la-nueva-tecnologia-de-google\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/utel.mx\/blog\/dia-a-dia\/glass-la-nueva-tecnologia-de-google\/#primaryimage","url":"https:\/\/utel.mx\/blog\/wp-content\/uploads\/2013\/06\/shutterstock_140433580.jpg","contentUrl":"https:\/\/utel.mx\/blog\/wp-content\/uploads\/2013\/06\/shutterstock_140433580.jpg","width":2700,"height":1800},{"@type":"BreadcrumbList","@id":"https:\/\/utel.mx\/blog\/dia-a-dia\/glass-la-nueva-tecnologia-de-google\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/utel.mx\/blog\/"},{"@type":"ListItem","position":2,"name":"Glass, la nueva tecnolog\u00eda de Google"}]},{"@type":"WebSite","@id":"https:\/\/utel.mx\/blog\/#website","url":"https:\/\/utel.mx\/blog\/","name":"BLOG | Utel","description":"Blog UTEL Universidad en L\u00ednea","publisher":{"@id":"https:\/\/utel.mx\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/utel.mx\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/utel.mx\/blog\/#organization","name":"BLOG | Utel","url":"https:\/\/utel.mx\/blog\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/utel.mx\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/utel.mx\/blog\/wp-content\/uploads\/2023\/03\/cropped-logo-blog.png","contentUrl":"https:\/\/utel.mx\/blog\/wp-content\/uploads\/2023\/03\/cropped-logo-blog.png","width":237,"height":64,"caption":"BLOG | Utel"},"image":{"@id":"https:\/\/utel.mx\/blog\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/utel.mx\/blog\/#\/schema\/person\/e5b3d8d918f13bd0b0f4724daa90dd95","name":"Invitados UTEL","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/utel.mx\/blog\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/781456f1128be5a332ab27ea8b902597?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/781456f1128be5a332ab27ea8b902597?s=96&d=mm&r=g","caption":"Invitados UTEL"},"description":"Invitados . Colaboraciones por parte de invitados de la Comunidad UTEL"}]}},"_links":{"self":[{"href":"https:\/\/utel.mx\/blog\/wp-json\/wp\/v2\/posts\/2183","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/utel.mx\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/utel.mx\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/utel.mx\/blog\/wp-json\/wp\/v2\/users\/40"}],"replies":[{"embeddable":true,"href":"https:\/\/utel.mx\/blog\/wp-json\/wp\/v2\/comments?post=2183"}],"version-history":[{"count":1,"href":"https:\/\/utel.mx\/blog\/wp-json\/wp\/v2\/posts\/2183\/revisions"}],"predecessor-version":[{"id":44991,"href":"https:\/\/utel.mx\/blog\/wp-json\/wp\/v2\/posts\/2183\/revisions\/44991"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/utel.mx\/blog\/wp-json\/wp\/v2\/media\/2188"}],"wp:attachment":[{"href":"https:\/\/utel.mx\/blog\/wp-json\/wp\/v2\/media?parent=2183"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/utel.mx\/blog\/wp-json\/wp\/v2\/categories?post=2183"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/utel.mx\/blog\/wp-json\/wp\/v2\/tags?post=2183"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}