{"id":35012,"date":"2020-08-24T23:38:50","date_gmt":"2020-08-24T23:38:50","guid":{"rendered":"http:\/\/utel.mx\/blog\/?p=35012"},"modified":"2023-03-10T17:11:45","modified_gmt":"2023-03-10T17:11:45","slug":"la-importancia-de-la-omnicanalidad-en-la-nueva-realidad","status":"publish","type":"post","link":"https:\/\/utel.mx\/blog\/tendencias\/la-importancia-de-la-omnicanalidad-en-la-nueva-realidad\/","title":{"rendered":"La importancia de la omnicanalidad en la nueva realidad"},"content":{"rendered":"<h2 style=\"text-align: justify;\"><span style=\"color: #333333;\">La pandemia ha tra\u00eddo consigo un cambio radical en los h\u00e1bitos de compra en la regi\u00f3n.<\/span><\/h2>\n<p style=\"text-align: justify;\"><span style=\"color: #333333;\">En la actualidad, hemos visto limitadas las interacciones de todo tipo; realizar transacciones bancarias, comprar medicamentos en las farmacias, adquirir electrodom\u00e9sticos o comprar en restaurantes de manera f\u00edsica no es lo mismo que hace unos meses. Se redujo el comercio presencial, incluso lleg\u00f3 a ser nulo en ciertos pa\u00edses de la regi\u00f3n Latinoamericana, esto con el fin de evitar la exposici\u00f3n de las personas a contagios de Covid-19.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #333333;\">Sin embargo, las consecuencias fueron negativas para los comercios que no estaban preparados ni ten\u00edan una estrategia digital. Dirigir los esfuerzos de los negocios hacia un enfoque omnicanal ofrece a los consumidores de los productos y servicios, experiencias \u00fanicas y \u00fatiles, en tiempos donde mantener el distanciamiento social es clave para la sociedad.\u00a0<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #333333;\">Un estudio hecho por Mercado libre indic\u00f3 que la pandemia en la regi\u00f3n gener\u00f3 1.7 millones de usuarios que se han convertido en consumidores digitales. La llegada del Covid-19 a los distintos pa\u00edses de Am\u00e9rica Latina modific\u00f3 los h\u00e1bitos de consumo. Quedarse en casa para prevenir el contagio ha hecho que la compra online se convierta en la alternativa favorita de los usuarios para adquirir productos de todo tipo en comercios minoristas, mayoristas, servicios p\u00fablicos y banca.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #333333;\">\u201cHemos visto un cambio significativo en el comportamiento de los consumidores latinoamericanos durante este periodo de aislamiento social. Las categor\u00edas que antes era demandadas con normalidad como los celulares, por ejemplo, han perdido parte de su relevancia y los usuarios est\u00e1n volcando sus compras a \u00edtems m\u00e1s significativos en esta pandemia, como productos de salud, alimentos y art\u00edculos de entretenci\u00f3n\u201d, asegur\u00f3 el Director General de Mercado Libre, Alan Meyer.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #333333;\">Asimismo, un estudio de la\u00a0Asociaci\u00f3n Mexicana de Venta Online (AMVO)\u00a0indica que 42% de los compradores mexicanos en l\u00ednea inician sus compras por internet y recogen el producto en una tienda f\u00edsica.\u00a0<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #333333;\">Hoy en d\u00eda Latinoam\u00e9rica, una regi\u00f3n donde el 67% de las personas tiene acceso a internet, 43% cuentan con smartphone y una pandemia que pone en jaque y obliga a las empresas y emprendedores a replantear sus estrategias y transformarse digitalmente, aplicar la omnicanalidad es vital para sobrevivir en el mercado.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #333333;\">La experiencia de compra &#8211; venta a\u00f1os atr\u00e1s era de un solo canal, a medida que pasaron los a\u00f1os conocimos la multicanalidad; es decir, distintos medios de compra con estrategia distinta en cada uno de ellos.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #333333;\">Las empresas, ya sean grandes o peque\u00f1as, tienen que estar presentes brindando el mismo servicio en todos los canales donde su <em>target<\/em> est\u00e1. Esto es importante, porque al cliente\/ consumidor ya no lo eligen; es \u00e9l quien elige, por eso se informa y mientras m\u00e1s herramientas posee mejores decisiones tomar\u00e1. <strong>Los clientes buscan flexibilidad, rapidez, seguridad y confianza en sus procesos de compra. <\/strong><\/span><\/p>\n<h2 style=\"text-align: justify;\"><strong><span style=\"color: #333333;\">\u00bfA qu\u00e9 nos referimos con omnicanalidad cuando hablamos de esto?<\/span><\/strong><\/h2>\n<p style=\"text-align: justify;\"><span style=\"color: #333333;\">La omnicanalidad significa tener <strong>distintos m\u00e9todos de compra para los clientes<\/strong>; pero la misma estrategia y experiencia \u00fanica en todos los canales; ya sea, <em>e-commerce<\/em>, tienda f\u00edsica, aplicativo m\u00f3vil, <em>call centers<\/em>, redes sociales y <em>marketplaces<\/em>. De hecho, la omnicanalidad se aplica mucho en el retail o consumo masivo; sin embargo, hemos visto que los bancos, empresas de servicios p\u00fablico como agua y electricidad, farmacias, etc., ya la estaban aplicando desde antes de la pandemia.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #333333;\">El objetivo del marketing multicanal y omnicanal es el mismo: la venta a trav\u00e9s de los canales de comunicaci\u00f3n online y offline. Sin embargo, la diferencia es la experiencia del cliente.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #333333;\">El prop\u00f3sito es difundir el mensaje a trav\u00e9s del m\u00e1ximo n\u00famero de canales posible. <strong>El marketing omnicanal es la estrategia constante que se encarga de conocer al cliente y ofrecer productos a trav\u00e9s de los distintos canales que van acorde a su personalidad y necesidades.<\/strong> El consumidor o usuario toma la decisi\u00f3n de en qu\u00e9 canal ponerse en contacto, sin importar d\u00f3nde o c\u00f3mo est\u00e9 interactuando con la marca.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #333333;\">Las estrategias de omnicanalidad tienen ahora el reto de llenar los vac\u00edos que deja la falta de espacios f\u00edsicos para contacto personal. Adicionalmente, los efectos psicol\u00f3gicos del confinamiento y distanciamiento social sobre los empleados y clientes hacen que la atenci\u00f3n al cliente pueda ser a\u00fan m\u00e1s desafiante y requerir agentes con m\u00e1s habilidades de empat\u00eda y nuevos canales de comunicaci\u00f3n (P. Santos, La omnicanalidad permite a las empresas crecer durante la pandemia, 2020).<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #333333;\">Los clientes leales, son clientes satisfechos y generan mayores ingresos para las empresas, \u00bfc\u00f3mo los mantenemos fieles? Poni\u00e9ndonos en sus zapatos, interactuando adecuadamente con ellos. Suena sencillo, la teor\u00eda la sabemos, pero lo dif\u00edcil es recordarlo en la pr\u00e1ctica. Por ello es recomendable identificar al cliente o usuario, sus h\u00e1bitos, lo que espera, incomoda y desea obtener. Con esta informaci\u00f3n realizar mapas de empat\u00eda, rutas del cliente, canvas y preguntar cuantas veces sea necesario a nuestro p\u00fablico objetivo, mientras m\u00e1s se conozca a este, mejores t\u00e1cticas se podr\u00e1n desarrollar por y para \u00e9l.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #333333;\"><strong>Claudia Torrej\u00f3n Re\u00e1tegui<\/strong><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #333333;\"><strong>LinkedIn: <\/strong><a style=\"color: #333333;\" href=\"https:\/\/www.linkedin.com\/in\/claudiatorrejon\/\">https:\/\/www.linkedin.com\/in\/claudiatorrejon\/<br \/>\n<\/a><\/span><span style=\"color: #333333;\"><strong>Twitter:<\/strong> <a style=\"color: #333333;\" href=\"https:\/\/twitter.com\/cltorrejon3\">https:\/\/twitter.com\/cltorrejon3<\/a><\/span><\/p>\n<p style=\"text-align: left;\"><span style=\"color: #333333;\"><strong>Fuente:<\/strong><\/span><\/p>\n<p style=\"text-align: left;\">&#8211; P\u00e1gina web SAP Blogs.com , Latin America (Consulta 12 de agosto, 2020) <a style=\"font-size: 16px; color: #333333;\" href=\"https:\/\/news.sap.com\/latinamerica\/2020\/03\/como-lograr-omnicanalidad-y-una-mejor-experiencia-al-cliente-flexi-tiene-la-respuesta\/\">https:\/\/news.sap.com\/latinamerica\/2020\/03\/como-lograr-omnicanalidad-y-una-mejor-experiencia-al-cliente-flexi-tiene-la-respuesta\/<\/a><\/p>\n<p style=\"text-align: left;\"><span style=\"color: #333333;\">&#8211; P\u00e1gina web IA Latam.com (Consulta 13 de agosto, 2020) <a style=\"color: #333333;\" href=\"https:\/\/ia-latam.com\/2020\/04\/29\/la-pandemia-genero-17-millones-nuevos-compradores-online-en-america-latina\/\">https:\/\/ia-latam.com\/2020\/04\/29\/la-pandemia-genero-17-millones-nuevos-compradores-online-en-america-latina\/<\/a><\/span><\/p>\n<p style=\"text-align: left;\"><span style=\"color: #333333;\">&#8211; P\u00e1gina web Statista.com (Consulta 13 de agosto, 2020) <a style=\"color: #333333;\" href=\"https:\/\/es.statista.com\/grafico\/10071\/la-generalizacion-del-smartphone-en-latinoamerica\/\">https:\/\/es.statista.com\/grafico\/10071\/la-generalizacion-del-smartphone-en-latinoamerica\/<\/a><\/span><\/p>\n<p style=\"text-align: left;\"><span style=\"color: #333333;\">&#8211; P\u00e1gina web Statista.com (Consulta 13 de agosto, 2020) <a style=\"color: #333333;\" href=\"https:\/\/es.statista.com\/grafico\/13903\/cuantos-usuarios-de-internet-hay-en-america-latina\/\">https:\/\/es.statista.com\/grafico\/13903\/cuantos-usuarios-de-internet-hay-en-america-latina\/<\/a><\/span><\/p>\n<p style=\"text-align: left;\"><span style=\"color: #333333;\">&#8211; P\u00e1gina web SAP Blogs.com , Latin America (Consulta 14 de agosto, 2020) <a style=\"color: #333333;\" href=\"https:\/\/news.sap.com\/latinamerica\/2019\/02\/la-importancia-de-ser-omnicanal-en-la-era-omni-digital-bl0g\/\">https:\/\/news.sap.com\/latinamerica\/2019\/02\/la-importancia-de-ser-omnicanal-en-la-era-omni-digital-bl0g\/<\/a><\/span><\/p>\n<p style=\"text-align: left;\"><span style=\"color: #333333;\">&#8211; Pablo Santos, columnista Diario virtual Dinero.com (Consulta 22 de agosto, 2020) <a style=\"color: #333333;\" href=\"https:\/\/www.dinero.com\/opinion\/columnistas\/articulo\/la-omnicanalidad-permite-a-las-empresas-crecer-por-pablo-santos\/296628\">https:\/\/www.dinero.com\/opinion\/columnistas\/articulo\/la-omnicanalidad-permite-a-las-empresas-crecer-por-pablo-santos\/296628<\/a><\/span><\/p>\n<div id=\"advads-1033554430\" class=\"advads-cta-lp-banner-form advads-entity-placement\"><a href=\"https:\/\/utel.mx\/blog\/admisiones-universidad-online\/?utm_source=blog&#038;utm_medium=CTAlink&#038;utm_campaign=MKTseo\" aria-label=\"Universidad en linea\"><img src=\"https:\/\/utel.mx\/blog\/wp-content\/uploads\/2025\/04\/universidad-en-linea-1.png\" alt=\"Universidad en linea\"  srcset=\"https:\/\/utel.mx\/blog\/wp-content\/uploads\/2025\/04\/universidad-en-linea-1.png 626w, https:\/\/utel.mx\/blog\/wp-content\/uploads\/2025\/04\/universidad-en-linea-1-420x168.png 420w\" sizes=\"(max-width: 626px) 100vw, 626px\" width=\"626\" height=\"250\"   \/><\/a><\/div>","protected":false},"excerpt":{"rendered":"<p> [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":35014,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-gradient":""}},"footnotes":""},"categories":[3505],"tags":[],"class_list":["post-35012","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-tendencias"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La importancia de la omnicanalidad en la nueva realidad - BLOG | Utel<\/title>\n<meta name=\"description\" content=\"La pandemia ha obligado a las empresas y emprendedores a replantear sus estrategias y transformarse, aplicar la omnicanalidad es vital para sobrevivir en el mercado. \u00a1Conoce de qu\u00e9 trata!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/utel.mx\/blog\/tendencias\/la-importancia-de-la-omnicanalidad-en-la-nueva-realidad\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La importancia de la omnicanalidad en la nueva realidad - BLOG | Utel\" \/>\n<meta property=\"og:description\" content=\"La pandemia ha obligado a las empresas y emprendedores a replantear sus estrategias y transformarse, aplicar la omnicanalidad es vital para sobrevivir en el mercado. \u00a1Conoce de qu\u00e9 trata!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/utel.mx\/blog\/tendencias\/la-importancia-de-la-omnicanalidad-en-la-nueva-realidad\/\" \/>\n<meta property=\"og:site_name\" content=\"BLOG | Utel\" \/>\n<meta property=\"article:published_time\" content=\"2020-08-24T23:38:50+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-03-10T17:11:45+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/utel.mx\/blog\/wp-content\/uploads\/2020\/08\/La-importancia-de-la-omnicanalidad-en-la-nueva-realidad.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"300\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Hayde\u00e9 (Editor)\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Hayde\u00e9 (Editor)\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/utel.mx\/blog\/tendencias\/la-importancia-de-la-omnicanalidad-en-la-nueva-realidad\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/utel.mx\/blog\/tendencias\/la-importancia-de-la-omnicanalidad-en-la-nueva-realidad\/\"},\"author\":{\"name\":\"Hayde\u00e9 (Editor)\",\"@id\":\"https:\/\/utel.mx\/blog\/#\/schema\/person\/9a4c3940beef2724facfef4f2ccec7da\"},\"headline\":\"La importancia de la omnicanalidad en la nueva realidad\",\"datePublished\":\"2020-08-24T23:38:50+00:00\",\"dateModified\":\"2023-03-10T17:11:45+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/utel.mx\/blog\/tendencias\/la-importancia-de-la-omnicanalidad-en-la-nueva-realidad\/\"},\"wordCount\":1004,\"publisher\":{\"@id\":\"https:\/\/utel.mx\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/utel.mx\/blog\/tendencias\/la-importancia-de-la-omnicanalidad-en-la-nueva-realidad\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/utel.mx\/blog\/wp-content\/uploads\/2020\/08\/La-importancia-de-la-omnicanalidad-en-la-nueva-realidad.jpg\",\"articleSection\":[\"Tendencias\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/utel.mx\/blog\/tendencias\/la-importancia-de-la-omnicanalidad-en-la-nueva-realidad\/\",\"url\":\"https:\/\/utel.mx\/blog\/tendencias\/la-importancia-de-la-omnicanalidad-en-la-nueva-realidad\/\",\"name\":\"La importancia de la omnicanalidad en la nueva realidad - BLOG | Utel\",\"isPartOf\":{\"@id\":\"https:\/\/utel.mx\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/utel.mx\/blog\/tendencias\/la-importancia-de-la-omnicanalidad-en-la-nueva-realidad\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/utel.mx\/blog\/tendencias\/la-importancia-de-la-omnicanalidad-en-la-nueva-realidad\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/utel.mx\/blog\/wp-content\/uploads\/2020\/08\/La-importancia-de-la-omnicanalidad-en-la-nueva-realidad.jpg\",\"datePublished\":\"2020-08-24T23:38:50+00:00\",\"dateModified\":\"2023-03-10T17:11:45+00:00\",\"description\":\"La pandemia ha obligado a las empresas y emprendedores a replantear sus estrategias y transformarse, aplicar la omnicanalidad es vital para sobrevivir en el mercado. \u00a1Conoce de qu\u00e9 trata!\",\"breadcrumb\":{\"@id\":\"https:\/\/utel.mx\/blog\/tendencias\/la-importancia-de-la-omnicanalidad-en-la-nueva-realidad\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/utel.mx\/blog\/tendencias\/la-importancia-de-la-omnicanalidad-en-la-nueva-realidad\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/utel.mx\/blog\/tendencias\/la-importancia-de-la-omnicanalidad-en-la-nueva-realidad\/#primaryimage\",\"url\":\"https:\/\/utel.mx\/blog\/wp-content\/uploads\/2020\/08\/La-importancia-de-la-omnicanalidad-en-la-nueva-realidad.jpg\",\"contentUrl\":\"https:\/\/utel.mx\/blog\/wp-content\/uploads\/2020\/08\/La-importancia-de-la-omnicanalidad-en-la-nueva-realidad.jpg\",\"width\":600,\"height\":300,\"caption\":\"La importancia de la omnicanalidad en la nueva realidad\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/utel.mx\/blog\/tendencias\/la-importancia-de-la-omnicanalidad-en-la-nueva-realidad\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/utel.mx\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La importancia de la omnicanalidad en la nueva realidad\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/utel.mx\/blog\/#website\",\"url\":\"https:\/\/utel.mx\/blog\/\",\"name\":\"BLOG | Utel\",\"description\":\"Blog UTEL Universidad en L\u00ednea\",\"publisher\":{\"@id\":\"https:\/\/utel.mx\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/utel.mx\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/utel.mx\/blog\/#organization\",\"name\":\"BLOG | Utel\",\"url\":\"https:\/\/utel.mx\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/utel.mx\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/utel.mx\/blog\/wp-content\/uploads\/2023\/03\/cropped-logo-blog.png\",\"contentUrl\":\"https:\/\/utel.mx\/blog\/wp-content\/uploads\/2023\/03\/cropped-logo-blog.png\",\"width\":237,\"height\":64,\"caption\":\"BLOG | Utel\"},\"image\":{\"@id\":\"https:\/\/utel.mx\/blog\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/utel.mx\/blog\/#\/schema\/person\/9a4c3940beef2724facfef4f2ccec7da\",\"name\":\"Hayde\u00e9 (Editor)\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/utel.mx\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/ba63bb7f074f0dfa874cba0ef5d985a5?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/ba63bb7f074f0dfa874cba0ef5d985a5?s=96&d=mm&r=g\",\"caption\":\"Hayde\u00e9 (Editor)\"},\"description\":\"Licenciada en Ciencias de la Comunicaci\u00f3n\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La importancia de la omnicanalidad en la nueva realidad - BLOG | Utel","description":"La pandemia ha obligado a las empresas y emprendedores a replantear sus estrategias y transformarse, aplicar la omnicanalidad es vital para sobrevivir en el mercado. \u00a1Conoce de qu\u00e9 trata!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/utel.mx\/blog\/tendencias\/la-importancia-de-la-omnicanalidad-en-la-nueva-realidad\/","og_locale":"es_ES","og_type":"article","og_title":"La importancia de la omnicanalidad en la nueva realidad - BLOG | Utel","og_description":"La pandemia ha obligado a las empresas y emprendedores a replantear sus estrategias y transformarse, aplicar la omnicanalidad es vital para sobrevivir en el mercado. \u00a1Conoce de qu\u00e9 trata!","og_url":"https:\/\/utel.mx\/blog\/tendencias\/la-importancia-de-la-omnicanalidad-en-la-nueva-realidad\/","og_site_name":"BLOG | Utel","article_published_time":"2020-08-24T23:38:50+00:00","article_modified_time":"2023-03-10T17:11:45+00:00","og_image":[{"width":600,"height":300,"url":"https:\/\/utel.mx\/blog\/wp-content\/uploads\/2020\/08\/La-importancia-de-la-omnicanalidad-en-la-nueva-realidad.jpg","type":"image\/jpeg"}],"author":"Hayde\u00e9 (Editor)","twitter_misc":{"Written by":"Hayde\u00e9 (Editor)","Est. reading time":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/utel.mx\/blog\/tendencias\/la-importancia-de-la-omnicanalidad-en-la-nueva-realidad\/#article","isPartOf":{"@id":"https:\/\/utel.mx\/blog\/tendencias\/la-importancia-de-la-omnicanalidad-en-la-nueva-realidad\/"},"author":{"name":"Hayde\u00e9 (Editor)","@id":"https:\/\/utel.mx\/blog\/#\/schema\/person\/9a4c3940beef2724facfef4f2ccec7da"},"headline":"La importancia de la omnicanalidad en la nueva realidad","datePublished":"2020-08-24T23:38:50+00:00","dateModified":"2023-03-10T17:11:45+00:00","mainEntityOfPage":{"@id":"https:\/\/utel.mx\/blog\/tendencias\/la-importancia-de-la-omnicanalidad-en-la-nueva-realidad\/"},"wordCount":1004,"publisher":{"@id":"https:\/\/utel.mx\/blog\/#organization"},"image":{"@id":"https:\/\/utel.mx\/blog\/tendencias\/la-importancia-de-la-omnicanalidad-en-la-nueva-realidad\/#primaryimage"},"thumbnailUrl":"https:\/\/utel.mx\/blog\/wp-content\/uploads\/2020\/08\/La-importancia-de-la-omnicanalidad-en-la-nueva-realidad.jpg","articleSection":["Tendencias"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/utel.mx\/blog\/tendencias\/la-importancia-de-la-omnicanalidad-en-la-nueva-realidad\/","url":"https:\/\/utel.mx\/blog\/tendencias\/la-importancia-de-la-omnicanalidad-en-la-nueva-realidad\/","name":"La importancia de la omnicanalidad en la nueva realidad - BLOG | Utel","isPartOf":{"@id":"https:\/\/utel.mx\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/utel.mx\/blog\/tendencias\/la-importancia-de-la-omnicanalidad-en-la-nueva-realidad\/#primaryimage"},"image":{"@id":"https:\/\/utel.mx\/blog\/tendencias\/la-importancia-de-la-omnicanalidad-en-la-nueva-realidad\/#primaryimage"},"thumbnailUrl":"https:\/\/utel.mx\/blog\/wp-content\/uploads\/2020\/08\/La-importancia-de-la-omnicanalidad-en-la-nueva-realidad.jpg","datePublished":"2020-08-24T23:38:50+00:00","dateModified":"2023-03-10T17:11:45+00:00","description":"La pandemia ha obligado a las empresas y emprendedores a replantear sus estrategias y transformarse, aplicar la omnicanalidad es vital para sobrevivir en el mercado. \u00a1Conoce de qu\u00e9 trata!","breadcrumb":{"@id":"https:\/\/utel.mx\/blog\/tendencias\/la-importancia-de-la-omnicanalidad-en-la-nueva-realidad\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/utel.mx\/blog\/tendencias\/la-importancia-de-la-omnicanalidad-en-la-nueva-realidad\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/utel.mx\/blog\/tendencias\/la-importancia-de-la-omnicanalidad-en-la-nueva-realidad\/#primaryimage","url":"https:\/\/utel.mx\/blog\/wp-content\/uploads\/2020\/08\/La-importancia-de-la-omnicanalidad-en-la-nueva-realidad.jpg","contentUrl":"https:\/\/utel.mx\/blog\/wp-content\/uploads\/2020\/08\/La-importancia-de-la-omnicanalidad-en-la-nueva-realidad.jpg","width":600,"height":300,"caption":"La importancia de la omnicanalidad en la nueva realidad"},{"@type":"BreadcrumbList","@id":"https:\/\/utel.mx\/blog\/tendencias\/la-importancia-de-la-omnicanalidad-en-la-nueva-realidad\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/utel.mx\/blog\/"},{"@type":"ListItem","position":2,"name":"La importancia de la omnicanalidad en la nueva realidad"}]},{"@type":"WebSite","@id":"https:\/\/utel.mx\/blog\/#website","url":"https:\/\/utel.mx\/blog\/","name":"BLOG | Utel","description":"Blog UTEL Universidad en L\u00ednea","publisher":{"@id":"https:\/\/utel.mx\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/utel.mx\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/utel.mx\/blog\/#organization","name":"BLOG | Utel","url":"https:\/\/utel.mx\/blog\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/utel.mx\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/utel.mx\/blog\/wp-content\/uploads\/2023\/03\/cropped-logo-blog.png","contentUrl":"https:\/\/utel.mx\/blog\/wp-content\/uploads\/2023\/03\/cropped-logo-blog.png","width":237,"height":64,"caption":"BLOG | Utel"},"image":{"@id":"https:\/\/utel.mx\/blog\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/utel.mx\/blog\/#\/schema\/person\/9a4c3940beef2724facfef4f2ccec7da","name":"Hayde\u00e9 (Editor)","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/utel.mx\/blog\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/ba63bb7f074f0dfa874cba0ef5d985a5?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ba63bb7f074f0dfa874cba0ef5d985a5?s=96&d=mm&r=g","caption":"Hayde\u00e9 (Editor)"},"description":"Licenciada en Ciencias de la Comunicaci\u00f3n"}]}},"_links":{"self":[{"href":"https:\/\/utel.mx\/blog\/wp-json\/wp\/v2\/posts\/35012","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/utel.mx\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/utel.mx\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/utel.mx\/blog\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/utel.mx\/blog\/wp-json\/wp\/v2\/comments?post=35012"}],"version-history":[{"count":1,"href":"https:\/\/utel.mx\/blog\/wp-json\/wp\/v2\/posts\/35012\/revisions"}],"predecessor-version":[{"id":46297,"href":"https:\/\/utel.mx\/blog\/wp-json\/wp\/v2\/posts\/35012\/revisions\/46297"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/utel.mx\/blog\/wp-json\/wp\/v2\/media\/35014"}],"wp:attachment":[{"href":"https:\/\/utel.mx\/blog\/wp-json\/wp\/v2\/media?parent=35012"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/utel.mx\/blog\/wp-json\/wp\/v2\/categories?post=35012"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/utel.mx\/blog\/wp-json\/wp\/v2\/tags?post=35012"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}