{"id":35517,"date":"2020-10-26T23:34:11","date_gmt":"2020-10-26T23:34:11","guid":{"rendered":"http:\/\/utel.mx\/blog\/?p=35517"},"modified":"2023-03-10T17:11:33","modified_gmt":"2023-03-10T17:11:33","slug":"el-gran-impulso-de-la-transformacion-digital","status":"publish","type":"post","link":"https:\/\/utel.mx\/blog\/tendencias\/el-gran-impulso-de-la-transformacion-digital\/","title":{"rendered":"El gran impulso de la transformaci\u00f3n digital"},"content":{"rendered":"<h2 style=\"text-align: justify;\">La transformaci\u00f3n digital se ha convertido en uno de los pilares fundamentales para combatir los efectos de la pandemia, su correcta implementaci\u00f3n tiene como efecto potenciar los ingresos y optimizar las tareas a ejecutar, convirti\u00e9ndose\u00a0vital en una compa\u00f1\u00eda para sobrevivir y ser competitivas.<\/h2>\n<p style=\"text-align: justify;\"><span style=\"color: #333333;\">Los planes que conllevan a la transformaci\u00f3n digital de las empresas en todos los rubros, se vieron acelerados por la crisis sanitaria global en la que vivimos. Esta transformaci\u00f3n ha permitido que algunas compa\u00f1\u00edas se mantengan activas en el mercado durante la pandemia y para que contin\u00faen bajo este nuevo lineamiento, es casi una obligaci\u00f3n que ingresen de lleno a la virtualidad.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #333333;\">La manera en que se ejecutan los negocios ha cambiado, la digitalizaci\u00f3n se ha convertido en uno de los pilares para combatir los efectos de la pandemia dado que potencia los ingresos y brinda una mayor eficiencia en tiempos donde la mayor\u00eda de empresas se enfrentan a diversos cambios. De igual manera, en las formas de comunicaci\u00f3n y comportamientos, antes solo se hablaba de la virtualidad como un concepto, hoy en d\u00eda ya existen proyectos digitales implementados y en operaci\u00f3n.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #333333;\">El presidente del Consejo de Ministros de Per\u00fa, Walter Martos Ruiz, afirma que la transformaci\u00f3n digital en el Per\u00fa permitir\u00e1 hacer frente a la pandemia, prevenir nuevos brotes, impulsar la reactivaci\u00f3n econ\u00f3mica y generar el bienestar de la poblaci\u00f3n. \u00abComo Ejecutivo, tenemos el compromiso de la generaci\u00f3n de cambios estructurales en temas tecnol\u00f3gicos y de innovaci\u00f3n\u00bb, agrega, al indicar que es imprescindible introducir herramientas tecnol\u00f3gicas para el bienestar de los peruanos. (Radio Nacional, 2020)<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #333333;\">Estas tecnolog\u00edas cada vez tienen mayor accesibilidad, se pueden personalizar y en ocasiones son r\u00e1pidas de implementar. De hecho, la inversi\u00f3n a realizar para lograr una \u00f3ptima digitalizaci\u00f3n en cada empresa es diferente, se debe tener conocimiento del sector, el tama\u00f1o y el recurso humano que se posee.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #333333;\">\u201cAdopci\u00f3n de la Transformaci\u00f3n Digital\u201d fue un estudio hecho por InterNexa (2020), en el cual se indica que las estrategias digitales reflejan distintos niveles de evoluci\u00f3n dependiendo del tama\u00f1o de las compa\u00f1\u00edas. Los sectores que aceleraron su transformaci\u00f3n digital en medio de la pandemia fueron los de educaci\u00f3n, banca, retail y telecomunicaciones, los resultados del estudio indican que el 51% de las grandes empresas est\u00e1n en la fase de \u201cTransformAcci\u00f3n\u201d, que permite tener resultados y consolidar procesos. Solo el 21% de las medianas y el 53% de las peque\u00f1as y las micro empresas se ubican en esta misma etapa.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #333333;\">Un claro ejemplo de \u00e9xito en Latinoam\u00e9rica es el Banco BBVA en Argentina que decidi\u00f3 dar un gran paso hacia el futuro incorporando los Servicios de Captura y Contenido de Xerox. El banco est\u00e1 en camino de eliminar los formularios de papel de sus 251 sucursales, lo que produjo una reducci\u00f3n del tr\u00e1mite de 40 a 10 minutos. Adem\u00e1s, el proceso de mantenimiento de documentaci\u00f3n del banco se redujo de 10 a 1 minuto. Esta transformaci\u00f3n digital significa un enorme beneficio no solo para la empresa, sino para los clientes, ofreci\u00e9ndoles una mejor experiencia y una realizaci\u00f3n de tr\u00e1mites m\u00e1s clara, eficiente y transparente (Xerox, 2020).<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #333333;\">Otro sector que tambi\u00e9n se benefici\u00f3 plenamente de esta transici\u00f3n fue el de entrega de comida online. En Estados Unidos, Instacart, una empresa que entrega alimentos a domicilio que logr\u00f3 tener ingresos por 225 millones de d\u00f3lares, elev\u00f3 su valoraci\u00f3n a casi el doble, a 13,700 millones de d\u00f3lares, todo ello debido a su crecimiento impulsado por los efectos de la pandemia. (El Financiero, 2020)<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #333333;\">En ese sentido, la transformaci\u00f3n implica comprender cu\u00e1l es el activo m\u00e1s importante, analizarlo y crear nuevas experiencias que se adapten a los principales deseos y necesidades de las personas en el contexto actual. Definir qu\u00e9 se quiere lograr, luego c\u00f3mo se va a lograr (estrategia) y finalmente con qu\u00e9 se va a lograr (tecnolog\u00eda).<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #333333;\">Joanne Collins, actual vicepresidenta ejecutiva y directora comercial de Xerox, concluye diciendo: \u201cNo importa la organizaci\u00f3n, inevitablemente hay una gran cantidad de trabajo que podemos digitalizar. Casi todos los procesos pueden ser digitalizados y automatizados de alguna manera, lo que hace posible hacer mucho m\u00e1s usando menos tiempo y dinero. Eso es absolutamente cr\u00edtico en un momento en que cada d\u00f3lar debe ser contabilizado y la creatividad de cada miembro del personal humano debe ser comprometida al m\u00e1ximo\u201d.<\/span><\/p>\n<p><center><!--HubSpot Call-to-Action Code --><span id=\"hs-cta-wrapper-88e7d4cb-d2db-43ff-a0a3-620f769ce8f7\" class=\"hs-cta-wrapper\"><span id=\"hs-cta-88e7d4cb-d2db-43ff-a0a3-620f769ce8f7\" class=\"hs-cta-node hs-cta-88e7d4cb-d2db-43ff-a0a3-620f769ce8f7\"><!-- [if lte IE 8]>\n\n\n<div id=\"hs-cta-ie-element\"><\/div>\n\n\n<![endif]--><a href=\"https:\/\/cta-redirect.hubspot.com\/cta\/redirect\/568441\/88e7d4cb-d2db-43ff-a0a3-620f769ce8f7\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" id=\"hs-cta-img-88e7d4cb-d2db-43ff-a0a3-620f769ce8f7\" class=\"hs-cta-img\" style=\"border-width: 0px;\" src=\"https:\/\/no-cache.hubspot.com\/cta\/default\/568441\/88e7d4cb-d2db-43ff-a0a3-620f769ce8f7.png\" alt=\"\u00a1Quiero saber m\u00e1s de UTEL!\" \/><\/a><\/span><script src=\"https:\/\/js.hscta.net\/cta\/current.js\" charset=\"utf-8\"><\/script><script type=\"text\/javascript\">\/\/ <![CDATA[\nhbspt.cta.load(568441, '88e7d4cb-d2db-43ff-a0a3-620f769ce8f7', {});\n\/\/ ]]><\/script><\/span><!-- end HubSpot Call-to-Action Code --><\/center><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #333333;\"><strong>Ricardo Bobadilla<br \/>\nEquipo Branding &amp; PR UTEL Internacional<\/strong><\/span><\/p>\n<h5 style=\"text-align: justify;\"><span style=\"color: #333333;\"><strong>Referencias<\/strong><\/span><\/h5>\n<h5 style=\"text-align: justify;\"><span style=\"color: #333333;\">Transformaci\u00f3n digital y ciencia de datos: claves para el nuevo mundo de negocios. (2020). <em>La Voz.<\/em> Recuperado de <a style=\"color: #333333;\" href=\"https:\/\/www.lavoz.com.ar\/espacio-publicidad\/transformacion-digital-y-ciencia-de-datos-claves-para-nuevo-mundo-de-negocios\">https:\/\/www.lavoz.com.ar\/espacio-publicidad\/transformacion-digital-y-ciencia-de-datos-claves-para-nuevo-mundo-de-negocios<\/a><\/span><\/h5>\n<h5 style=\"text-align: justify;\"><span style=\"color: #333333;\">Transformaci\u00f3n digital: el requisito fundamental es el coraje para comenzar. (2020). <em>Expreso.<\/em> Recuperado de <a style=\"color: #333333;\" href=\"https:\/\/www.expreso.com.pe\/tecnologia\/transformacion-digital-el-requisito-fundamental-es-el-coraje-para-comenzar\/\">https:\/\/www.expreso.com.pe\/tecnologia\/transformacion-digital-el-requisito-fundamental-es-el-coraje-para-comenzar\/<\/a><\/span><\/h5>\n<h5 style=\"text-align: justify;\"><span style=\"color: #333333;\">\u00bfEs realmente necesaria la transformaci\u00f3n digital en las empresas? (2020). <em>Internexa.<\/em> Recuperado de <a style=\"color: #333333;\" href=\"https:\/\/www.internexa.com\/blogs\/es-realmente-necesaria-la-transformacion-digital-en-las-empresas\/\">https:\/\/www.internexa.com\/blogs\/es-realmente-necesaria-la-transformacion-digital-en-las-empresas\/<\/a><\/span><\/h5>\n<h5 style=\"text-align: justify;\"><span style=\"color: #333333;\">Cornershop, el \u201cpasajero\u201d que desea Uber. (2020). <em>El Financiero.<\/em> Recuperado de <a style=\"color: #333333;\" href=\"https:\/\/www.elfinanciero.com.mx\/tech\/cornershop-el-pasajero-que-desea-uber\">https:\/\/www.elfinanciero.com.mx\/tech\/cornershop-el-pasajero-que-desea-uber<\/a><\/span><\/h5>\n<p style=\"text-align: justify;\"><span style=\"color: #333333;\">\u00a0<\/span><\/p>\n<div id=\"advads-696691503\" class=\"advads-cta-lp-banner-form advads-entity-placement\"><a href=\"https:\/\/utel.mx\/blog\/admisiones-universidad-online\/?utm_source=blog&#038;utm_medium=CTAlink&#038;utm_campaign=MKTseo\" aria-label=\"Universidad en linea\"><img src=\"https:\/\/utel.mx\/blog\/wp-content\/uploads\/2025\/04\/universidad-en-linea-1.png\" alt=\"Universidad en linea\"  srcset=\"https:\/\/utel.mx\/blog\/wp-content\/uploads\/2025\/04\/universidad-en-linea-1.png 626w, https:\/\/utel.mx\/blog\/wp-content\/uploads\/2025\/04\/universidad-en-linea-1-420x168.png 420w\" sizes=\"(max-width: 626px) 100vw, 626px\" width=\"626\" height=\"250\"   \/><\/a><\/div>","protected":false},"excerpt":{"rendered":"<p> [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":35520,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-gradient":""}},"footnotes":""},"categories":[3505],"tags":[],"class_list":["post-35517","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-tendencias"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>El gran impulso de la transformaci\u00f3n digital - BLOG | Utel<\/title>\n<meta name=\"description\" content=\"El impulso de la transformaci\u00f3n digital se ha convertido en un gran aliado para las compa\u00f1\u00edas, estableciendo nuevas estrategias y haci\u00e9ndolas m\u00e1s competitivas.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/utel.mx\/blog\/tendencias\/el-gran-impulso-de-la-transformacion-digital\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El gran impulso de la transformaci\u00f3n digital - BLOG | Utel\" \/>\n<meta property=\"og:description\" content=\"El impulso de la transformaci\u00f3n digital se ha convertido en un gran aliado para las compa\u00f1\u00edas, estableciendo nuevas estrategias y haci\u00e9ndolas m\u00e1s competitivas.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/utel.mx\/blog\/tendencias\/el-gran-impulso-de-la-transformacion-digital\/\" \/>\n<meta property=\"og:site_name\" content=\"BLOG | Utel\" \/>\n<meta property=\"article:published_time\" content=\"2020-10-26T23:34:11+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-03-10T17:11:33+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/utel.mx\/blog\/wp-content\/uploads\/2020\/10\/Headers_Octubre20_28_1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"300\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Hayde\u00e9 (Editor)\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Hayde\u00e9 (Editor)\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/utel.mx\/blog\/tendencias\/el-gran-impulso-de-la-transformacion-digital\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/utel.mx\/blog\/tendencias\/el-gran-impulso-de-la-transformacion-digital\/\"},\"author\":{\"name\":\"Hayde\u00e9 (Editor)\",\"@id\":\"https:\/\/utel.mx\/blog\/#\/schema\/person\/9a4c3940beef2724facfef4f2ccec7da\"},\"headline\":\"El gran impulso de la transformaci\u00f3n digital\",\"datePublished\":\"2020-10-26T23:34:11+00:00\",\"dateModified\":\"2023-03-10T17:11:33+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/utel.mx\/blog\/tendencias\/el-gran-impulso-de-la-transformacion-digital\/\"},\"wordCount\":858,\"publisher\":{\"@id\":\"https:\/\/utel.mx\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/utel.mx\/blog\/tendencias\/el-gran-impulso-de-la-transformacion-digital\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/utel.mx\/blog\/wp-content\/uploads\/2020\/10\/Headers_Octubre20_28_1.jpg\",\"articleSection\":[\"Tendencias\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/utel.mx\/blog\/tendencias\/el-gran-impulso-de-la-transformacion-digital\/\",\"url\":\"https:\/\/utel.mx\/blog\/tendencias\/el-gran-impulso-de-la-transformacion-digital\/\",\"name\":\"El gran impulso de la transformaci\u00f3n digital - BLOG | Utel\",\"isPartOf\":{\"@id\":\"https:\/\/utel.mx\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/utel.mx\/blog\/tendencias\/el-gran-impulso-de-la-transformacion-digital\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/utel.mx\/blog\/tendencias\/el-gran-impulso-de-la-transformacion-digital\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/utel.mx\/blog\/wp-content\/uploads\/2020\/10\/Headers_Octubre20_28_1.jpg\",\"datePublished\":\"2020-10-26T23:34:11+00:00\",\"dateModified\":\"2023-03-10T17:11:33+00:00\",\"description\":\"El impulso de la transformaci\u00f3n digital se ha convertido en un gran aliado para las compa\u00f1\u00edas, estableciendo nuevas estrategias y haci\u00e9ndolas m\u00e1s competitivas.\",\"breadcrumb\":{\"@id\":\"https:\/\/utel.mx\/blog\/tendencias\/el-gran-impulso-de-la-transformacion-digital\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/utel.mx\/blog\/tendencias\/el-gran-impulso-de-la-transformacion-digital\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/utel.mx\/blog\/tendencias\/el-gran-impulso-de-la-transformacion-digital\/#primaryimage\",\"url\":\"https:\/\/utel.mx\/blog\/wp-content\/uploads\/2020\/10\/Headers_Octubre20_28_1.jpg\",\"contentUrl\":\"https:\/\/utel.mx\/blog\/wp-content\/uploads\/2020\/10\/Headers_Octubre20_28_1.jpg\",\"width\":600,\"height\":300,\"caption\":\"El gran impulso de la transformaci\u00f3n digital\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/utel.mx\/blog\/tendencias\/el-gran-impulso-de-la-transformacion-digital\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/utel.mx\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El gran impulso de la transformaci\u00f3n digital\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/utel.mx\/blog\/#website\",\"url\":\"https:\/\/utel.mx\/blog\/\",\"name\":\"BLOG | Utel\",\"description\":\"Blog UTEL Universidad en L\u00ednea\",\"publisher\":{\"@id\":\"https:\/\/utel.mx\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/utel.mx\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/utel.mx\/blog\/#organization\",\"name\":\"BLOG | Utel\",\"url\":\"https:\/\/utel.mx\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/utel.mx\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/utel.mx\/blog\/wp-content\/uploads\/2023\/03\/cropped-logo-blog.png\",\"contentUrl\":\"https:\/\/utel.mx\/blog\/wp-content\/uploads\/2023\/03\/cropped-logo-blog.png\",\"width\":237,\"height\":64,\"caption\":\"BLOG | Utel\"},\"image\":{\"@id\":\"https:\/\/utel.mx\/blog\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/utel.mx\/blog\/#\/schema\/person\/9a4c3940beef2724facfef4f2ccec7da\",\"name\":\"Hayde\u00e9 (Editor)\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/utel.mx\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/ba63bb7f074f0dfa874cba0ef5d985a5?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/ba63bb7f074f0dfa874cba0ef5d985a5?s=96&d=mm&r=g\",\"caption\":\"Hayde\u00e9 (Editor)\"},\"description\":\"Licenciada en Ciencias de la Comunicaci\u00f3n\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El gran impulso de la transformaci\u00f3n digital - BLOG | Utel","description":"El impulso de la transformaci\u00f3n digital se ha convertido en un gran aliado para las compa\u00f1\u00edas, estableciendo nuevas estrategias y haci\u00e9ndolas m\u00e1s competitivas.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/utel.mx\/blog\/tendencias\/el-gran-impulso-de-la-transformacion-digital\/","og_locale":"es_ES","og_type":"article","og_title":"El gran impulso de la transformaci\u00f3n digital - BLOG | Utel","og_description":"El impulso de la transformaci\u00f3n digital se ha convertido en un gran aliado para las compa\u00f1\u00edas, estableciendo nuevas estrategias y haci\u00e9ndolas m\u00e1s competitivas.","og_url":"https:\/\/utel.mx\/blog\/tendencias\/el-gran-impulso-de-la-transformacion-digital\/","og_site_name":"BLOG | Utel","article_published_time":"2020-10-26T23:34:11+00:00","article_modified_time":"2023-03-10T17:11:33+00:00","og_image":[{"width":600,"height":300,"url":"https:\/\/utel.mx\/blog\/wp-content\/uploads\/2020\/10\/Headers_Octubre20_28_1.jpg","type":"image\/jpeg"}],"author":"Hayde\u00e9 (Editor)","twitter_misc":{"Written by":"Hayde\u00e9 (Editor)","Est. reading time":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/utel.mx\/blog\/tendencias\/el-gran-impulso-de-la-transformacion-digital\/#article","isPartOf":{"@id":"https:\/\/utel.mx\/blog\/tendencias\/el-gran-impulso-de-la-transformacion-digital\/"},"author":{"name":"Hayde\u00e9 (Editor)","@id":"https:\/\/utel.mx\/blog\/#\/schema\/person\/9a4c3940beef2724facfef4f2ccec7da"},"headline":"El gran impulso de la transformaci\u00f3n digital","datePublished":"2020-10-26T23:34:11+00:00","dateModified":"2023-03-10T17:11:33+00:00","mainEntityOfPage":{"@id":"https:\/\/utel.mx\/blog\/tendencias\/el-gran-impulso-de-la-transformacion-digital\/"},"wordCount":858,"publisher":{"@id":"https:\/\/utel.mx\/blog\/#organization"},"image":{"@id":"https:\/\/utel.mx\/blog\/tendencias\/el-gran-impulso-de-la-transformacion-digital\/#primaryimage"},"thumbnailUrl":"https:\/\/utel.mx\/blog\/wp-content\/uploads\/2020\/10\/Headers_Octubre20_28_1.jpg","articleSection":["Tendencias"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/utel.mx\/blog\/tendencias\/el-gran-impulso-de-la-transformacion-digital\/","url":"https:\/\/utel.mx\/blog\/tendencias\/el-gran-impulso-de-la-transformacion-digital\/","name":"El gran impulso de la transformaci\u00f3n digital - BLOG | Utel","isPartOf":{"@id":"https:\/\/utel.mx\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/utel.mx\/blog\/tendencias\/el-gran-impulso-de-la-transformacion-digital\/#primaryimage"},"image":{"@id":"https:\/\/utel.mx\/blog\/tendencias\/el-gran-impulso-de-la-transformacion-digital\/#primaryimage"},"thumbnailUrl":"https:\/\/utel.mx\/blog\/wp-content\/uploads\/2020\/10\/Headers_Octubre20_28_1.jpg","datePublished":"2020-10-26T23:34:11+00:00","dateModified":"2023-03-10T17:11:33+00:00","description":"El impulso de la transformaci\u00f3n digital se ha convertido en un gran aliado para las compa\u00f1\u00edas, estableciendo nuevas estrategias y haci\u00e9ndolas m\u00e1s competitivas.","breadcrumb":{"@id":"https:\/\/utel.mx\/blog\/tendencias\/el-gran-impulso-de-la-transformacion-digital\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/utel.mx\/blog\/tendencias\/el-gran-impulso-de-la-transformacion-digital\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/utel.mx\/blog\/tendencias\/el-gran-impulso-de-la-transformacion-digital\/#primaryimage","url":"https:\/\/utel.mx\/blog\/wp-content\/uploads\/2020\/10\/Headers_Octubre20_28_1.jpg","contentUrl":"https:\/\/utel.mx\/blog\/wp-content\/uploads\/2020\/10\/Headers_Octubre20_28_1.jpg","width":600,"height":300,"caption":"El gran impulso de la transformaci\u00f3n digital"},{"@type":"BreadcrumbList","@id":"https:\/\/utel.mx\/blog\/tendencias\/el-gran-impulso-de-la-transformacion-digital\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/utel.mx\/blog\/"},{"@type":"ListItem","position":2,"name":"El gran impulso de la transformaci\u00f3n digital"}]},{"@type":"WebSite","@id":"https:\/\/utel.mx\/blog\/#website","url":"https:\/\/utel.mx\/blog\/","name":"BLOG | Utel","description":"Blog UTEL Universidad en L\u00ednea","publisher":{"@id":"https:\/\/utel.mx\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/utel.mx\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/utel.mx\/blog\/#organization","name":"BLOG | Utel","url":"https:\/\/utel.mx\/blog\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/utel.mx\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/utel.mx\/blog\/wp-content\/uploads\/2023\/03\/cropped-logo-blog.png","contentUrl":"https:\/\/utel.mx\/blog\/wp-content\/uploads\/2023\/03\/cropped-logo-blog.png","width":237,"height":64,"caption":"BLOG | Utel"},"image":{"@id":"https:\/\/utel.mx\/blog\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/utel.mx\/blog\/#\/schema\/person\/9a4c3940beef2724facfef4f2ccec7da","name":"Hayde\u00e9 (Editor)","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/utel.mx\/blog\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/ba63bb7f074f0dfa874cba0ef5d985a5?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ba63bb7f074f0dfa874cba0ef5d985a5?s=96&d=mm&r=g","caption":"Hayde\u00e9 (Editor)"},"description":"Licenciada en Ciencias de la Comunicaci\u00f3n"}]}},"_links":{"self":[{"href":"https:\/\/utel.mx\/blog\/wp-json\/wp\/v2\/posts\/35517","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/utel.mx\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/utel.mx\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/utel.mx\/blog\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/utel.mx\/blog\/wp-json\/wp\/v2\/comments?post=35517"}],"version-history":[{"count":1,"href":"https:\/\/utel.mx\/blog\/wp-json\/wp\/v2\/posts\/35517\/revisions"}],"predecessor-version":[{"id":46267,"href":"https:\/\/utel.mx\/blog\/wp-json\/wp\/v2\/posts\/35517\/revisions\/46267"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/utel.mx\/blog\/wp-json\/wp\/v2\/media\/35520"}],"wp:attachment":[{"href":"https:\/\/utel.mx\/blog\/wp-json\/wp\/v2\/media?parent=35517"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/utel.mx\/blog\/wp-json\/wp\/v2\/categories?post=35517"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/utel.mx\/blog\/wp-json\/wp\/v2\/tags?post=35517"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}