{"id":36417,"date":"2021-02-16T23:13:59","date_gmt":"2021-02-16T23:13:59","guid":{"rendered":"http:\/\/utel.mx\/blog\/?p=36417"},"modified":"2023-03-10T17:13:39","modified_gmt":"2023-03-10T17:13:39","slug":"alianza-estrategica-entre-felicity-360-y-utel-universidad-en-peru","status":"publish","type":"post","link":"https:\/\/utel.mx\/blog\/business-school\/alianza-estrategica-entre-felicity-360-y-utel-universidad-en-peru\/","title":{"rendered":"Convenio estrat\u00e9gico entre Felicity 360 y UTEL Universidad en Per\u00fa"},"content":{"rendered":"<h3><span style=\"color: #000000;\">Tenemos el compromiso de ofrecer educaci\u00f3n superior online de calidad a nivel internacional. Dentro de este desarrollo del talento humano y para potenciar las habilidades de nuestros alumnos, nos es muy importante fortalecer, en igual proporci\u00f3n, nuestro posicionamiento e identidad en los pa\u00edses donde nos encontramos, estableciendo lazos de confianza con organizaciones de prestigio.<\/span><\/h3>\n<p><span style=\"color: #000000;\">Estamos muy felices de anunciar el convenio corporativo entre UTEL Universidad y <\/span><span style=\"color: #339966;\"><strong><a style=\"color: #339966;\" href=\"https:\/\/www.felicity360.com\/\" target=\"_blank\" rel=\"noopener\">Felicity 360<\/a><\/strong><\/span><span style=\"color: #000000;\">, una consultora a nivel Latinoam\u00e9rica de Recursos Humanos y Comunicaciones, la cual entrega un servicio especializado en marketing relacional ayudando a las organizaciones a generar lazos s\u00f3lidos con sus colaboradores. Dentro de su posicionamiento en Per\u00fa, empresas destacadas como <strong>Est\u00e9e Lauder Companies, Hapag Lloyd <\/strong>y <strong>Agr\u00edcola Cerro Prieto<\/strong>, tendr\u00e1n beneficios exclusivos para estudiar nuestras especialidades 100% online, donde incluimos nuestra oferta acad\u00e9mica de Licenciaturas, Maestr\u00edas y Doctorados.<\/span><\/p>\n<p><span style=\"color: #000000;\">Agradecemos la confianza que esta gran organizaci\u00f3n y por creer en nuestra metodolog\u00eda de estudios que sigue trascendiendo fronteras y transformando vidas.<\/span><\/p>\n<p><strong>Visita el sitio de <span style=\"color: #339966;\"><a style=\"color: #339966;\" href=\"https:\/\/peru.utel.edu.mx\/\" target=\"_blank\" rel=\"noopener\">UTEL Per\u00fa<\/a><\/span> aqu\u00ed.<\/strong><\/p>\n<div id=\"advads-988960955\" class=\"advads-cta-lp-banner-form advads-entity-placement\"><a href=\"https:\/\/utel.mx\/blog\/admisiones-universidad-online\/?utm_source=blog&#038;utm_medium=CTAlink&#038;utm_campaign=MKTseo\" aria-label=\"Universidad en linea\"><img src=\"https:\/\/utel.mx\/blog\/wp-content\/uploads\/2025\/04\/universidad-en-linea-1.png\" alt=\"Universidad en linea\"  srcset=\"https:\/\/utel.mx\/blog\/wp-content\/uploads\/2025\/04\/universidad-en-linea-1.png 626w, https:\/\/utel.mx\/blog\/wp-content\/uploads\/2025\/04\/universidad-en-linea-1-420x168.png 420w\" sizes=\"(max-width: 626px) 100vw, 626px\" width=\"626\" height=\"250\"   \/><\/a><\/div>","protected":false},"excerpt":{"rendered":"<p> [&hellip;]<\/p>\n","protected":false},"author":82,"featured_media":36418,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-gradient":""}},"footnotes":""},"categories":[3461],"tags":[],"class_list":["post-36417","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-business-school"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Convenio estrat\u00e9gico entre Felicity 360 y UTEL Universidad en Per\u00fa - BLOG | Utel<\/title>\n<meta name=\"description\" content=\"Conoce los detalles de la alianza entre Felicity 360 y UTEL Per\u00fa\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/utel.mx\/blog\/business-school\/alianza-estrategica-entre-felicity-360-y-utel-universidad-en-peru\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Convenio estrat\u00e9gico entre Felicity 360 y UTEL Universidad en Per\u00fa - BLOG | Utel\" \/>\n<meta property=\"og:description\" content=\"Conoce los detalles de la alianza entre Felicity 360 y UTEL Per\u00fa\" \/>\n<meta property=\"og:url\" content=\"https:\/\/utel.mx\/blog\/business-school\/alianza-estrategica-entre-felicity-360-y-utel-universidad-en-peru\/\" \/>\n<meta property=\"og:site_name\" content=\"BLOG | Utel\" \/>\n<meta property=\"article:published_time\" content=\"2021-02-16T23:13:59+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-03-10T17:13:39+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/utel.mx\/blog\/wp-content\/uploads\/2021\/02\/Headers_Feb21_15_6-Per\u00fa.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"300\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"David Mora\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"David Mora\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/utel.mx\/blog\/business-school\/alianza-estrategica-entre-felicity-360-y-utel-universidad-en-peru\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/utel.mx\/blog\/business-school\/alianza-estrategica-entre-felicity-360-y-utel-universidad-en-peru\/\"},\"author\":{\"name\":\"David Mora\",\"@id\":\"https:\/\/utel.mx\/blog\/#\/schema\/person\/02ff4004657582a6dde2023933a23cea\"},\"headline\":\"Convenio estrat\u00e9gico entre Felicity 360 y UTEL Universidad en Per\u00fa\",\"datePublished\":\"2021-02-16T23:13:59+00:00\",\"dateModified\":\"2023-03-10T17:13:39+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/utel.mx\/blog\/business-school\/alianza-estrategica-entre-felicity-360-y-utel-universidad-en-peru\/\"},\"wordCount\":184,\"publisher\":{\"@id\":\"https:\/\/utel.mx\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/utel.mx\/blog\/business-school\/alianza-estrategica-entre-felicity-360-y-utel-universidad-en-peru\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/utel.mx\/blog\/wp-content\/uploads\/2021\/02\/Headers_Feb21_15_6-Per\u00fa.jpg\",\"articleSection\":[\"Business School\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/utel.mx\/blog\/business-school\/alianza-estrategica-entre-felicity-360-y-utel-universidad-en-peru\/\",\"url\":\"https:\/\/utel.mx\/blog\/business-school\/alianza-estrategica-entre-felicity-360-y-utel-universidad-en-peru\/\",\"name\":\"Convenio estrat\u00e9gico entre Felicity 360 y UTEL Universidad en Per\u00fa - BLOG | Utel\",\"isPartOf\":{\"@id\":\"https:\/\/utel.mx\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/utel.mx\/blog\/business-school\/alianza-estrategica-entre-felicity-360-y-utel-universidad-en-peru\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/utel.mx\/blog\/business-school\/alianza-estrategica-entre-felicity-360-y-utel-universidad-en-peru\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/utel.mx\/blog\/wp-content\/uploads\/2021\/02\/Headers_Feb21_15_6-Per\u00fa.jpg\",\"datePublished\":\"2021-02-16T23:13:59+00:00\",\"dateModified\":\"2023-03-10T17:13:39+00:00\",\"description\":\"Conoce los detalles de la alianza entre Felicity 360 y UTEL Per\u00fa\",\"breadcrumb\":{\"@id\":\"https:\/\/utel.mx\/blog\/business-school\/alianza-estrategica-entre-felicity-360-y-utel-universidad-en-peru\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/utel.mx\/blog\/business-school\/alianza-estrategica-entre-felicity-360-y-utel-universidad-en-peru\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/utel.mx\/blog\/business-school\/alianza-estrategica-entre-felicity-360-y-utel-universidad-en-peru\/#primaryimage\",\"url\":\"https:\/\/utel.mx\/blog\/wp-content\/uploads\/2021\/02\/Headers_Feb21_15_6-Per\u00fa.jpg\",\"contentUrl\":\"https:\/\/utel.mx\/blog\/wp-content\/uploads\/2021\/02\/Headers_Feb21_15_6-Per\u00fa.jpg\",\"width\":600,\"height\":300,\"caption\":\"Alianza Estrat\u00e9gica entre Felicity 360 y UTEL Universidad en Per\u00fa\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/utel.mx\/blog\/business-school\/alianza-estrategica-entre-felicity-360-y-utel-universidad-en-peru\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/utel.mx\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Convenio estrat\u00e9gico entre Felicity 360 y UTEL Universidad en Per\u00fa\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/utel.mx\/blog\/#website\",\"url\":\"https:\/\/utel.mx\/blog\/\",\"name\":\"BLOG | Utel\",\"description\":\"Blog UTEL Universidad en L\u00ednea\",\"publisher\":{\"@id\":\"https:\/\/utel.mx\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/utel.mx\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/utel.mx\/blog\/#organization\",\"name\":\"BLOG | Utel\",\"url\":\"https:\/\/utel.mx\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/utel.mx\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/utel.mx\/blog\/wp-content\/uploads\/2023\/03\/cropped-logo-blog.png\",\"contentUrl\":\"https:\/\/utel.mx\/blog\/wp-content\/uploads\/2023\/03\/cropped-logo-blog.png\",\"width\":237,\"height\":64,\"caption\":\"BLOG | Utel\"},\"image\":{\"@id\":\"https:\/\/utel.mx\/blog\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/utel.mx\/blog\/#\/schema\/person\/02ff4004657582a6dde2023933a23cea\",\"name\":\"David Mora\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/utel.mx\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/a26766025e096bd4334bd54509ff15a6?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/a26766025e096bd4334bd54509ff15a6?s=96&d=mm&r=g\",\"caption\":\"David Mora\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Convenio estrat\u00e9gico entre Felicity 360 y UTEL Universidad en Per\u00fa - BLOG | Utel","description":"Conoce los detalles de la alianza entre Felicity 360 y UTEL Per\u00fa","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/utel.mx\/blog\/business-school\/alianza-estrategica-entre-felicity-360-y-utel-universidad-en-peru\/","og_locale":"es_ES","og_type":"article","og_title":"Convenio estrat\u00e9gico entre Felicity 360 y UTEL Universidad en Per\u00fa - BLOG | Utel","og_description":"Conoce los detalles de la alianza entre Felicity 360 y UTEL Per\u00fa","og_url":"https:\/\/utel.mx\/blog\/business-school\/alianza-estrategica-entre-felicity-360-y-utel-universidad-en-peru\/","og_site_name":"BLOG | Utel","article_published_time":"2021-02-16T23:13:59+00:00","article_modified_time":"2023-03-10T17:13:39+00:00","og_image":[{"width":600,"height":300,"url":"https:\/\/utel.mx\/blog\/wp-content\/uploads\/2021\/02\/Headers_Feb21_15_6-Per\u00fa.jpg","type":"image\/jpeg"}],"author":"David Mora","twitter_misc":{"Written by":"David Mora","Est. reading time":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/utel.mx\/blog\/business-school\/alianza-estrategica-entre-felicity-360-y-utel-universidad-en-peru\/#article","isPartOf":{"@id":"https:\/\/utel.mx\/blog\/business-school\/alianza-estrategica-entre-felicity-360-y-utel-universidad-en-peru\/"},"author":{"name":"David Mora","@id":"https:\/\/utel.mx\/blog\/#\/schema\/person\/02ff4004657582a6dde2023933a23cea"},"headline":"Convenio estrat\u00e9gico entre Felicity 360 y UTEL Universidad en Per\u00fa","datePublished":"2021-02-16T23:13:59+00:00","dateModified":"2023-03-10T17:13:39+00:00","mainEntityOfPage":{"@id":"https:\/\/utel.mx\/blog\/business-school\/alianza-estrategica-entre-felicity-360-y-utel-universidad-en-peru\/"},"wordCount":184,"publisher":{"@id":"https:\/\/utel.mx\/blog\/#organization"},"image":{"@id":"https:\/\/utel.mx\/blog\/business-school\/alianza-estrategica-entre-felicity-360-y-utel-universidad-en-peru\/#primaryimage"},"thumbnailUrl":"https:\/\/utel.mx\/blog\/wp-content\/uploads\/2021\/02\/Headers_Feb21_15_6-Per\u00fa.jpg","articleSection":["Business School"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/utel.mx\/blog\/business-school\/alianza-estrategica-entre-felicity-360-y-utel-universidad-en-peru\/","url":"https:\/\/utel.mx\/blog\/business-school\/alianza-estrategica-entre-felicity-360-y-utel-universidad-en-peru\/","name":"Convenio estrat\u00e9gico entre Felicity 360 y UTEL Universidad en Per\u00fa - BLOG | Utel","isPartOf":{"@id":"https:\/\/utel.mx\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/utel.mx\/blog\/business-school\/alianza-estrategica-entre-felicity-360-y-utel-universidad-en-peru\/#primaryimage"},"image":{"@id":"https:\/\/utel.mx\/blog\/business-school\/alianza-estrategica-entre-felicity-360-y-utel-universidad-en-peru\/#primaryimage"},"thumbnailUrl":"https:\/\/utel.mx\/blog\/wp-content\/uploads\/2021\/02\/Headers_Feb21_15_6-Per\u00fa.jpg","datePublished":"2021-02-16T23:13:59+00:00","dateModified":"2023-03-10T17:13:39+00:00","description":"Conoce los detalles de la alianza entre Felicity 360 y UTEL Per\u00fa","breadcrumb":{"@id":"https:\/\/utel.mx\/blog\/business-school\/alianza-estrategica-entre-felicity-360-y-utel-universidad-en-peru\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/utel.mx\/blog\/business-school\/alianza-estrategica-entre-felicity-360-y-utel-universidad-en-peru\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/utel.mx\/blog\/business-school\/alianza-estrategica-entre-felicity-360-y-utel-universidad-en-peru\/#primaryimage","url":"https:\/\/utel.mx\/blog\/wp-content\/uploads\/2021\/02\/Headers_Feb21_15_6-Per\u00fa.jpg","contentUrl":"https:\/\/utel.mx\/blog\/wp-content\/uploads\/2021\/02\/Headers_Feb21_15_6-Per\u00fa.jpg","width":600,"height":300,"caption":"Alianza Estrat\u00e9gica entre Felicity 360 y UTEL Universidad en Per\u00fa"},{"@type":"BreadcrumbList","@id":"https:\/\/utel.mx\/blog\/business-school\/alianza-estrategica-entre-felicity-360-y-utel-universidad-en-peru\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/utel.mx\/blog\/"},{"@type":"ListItem","position":2,"name":"Convenio estrat\u00e9gico entre Felicity 360 y UTEL Universidad en Per\u00fa"}]},{"@type":"WebSite","@id":"https:\/\/utel.mx\/blog\/#website","url":"https:\/\/utel.mx\/blog\/","name":"BLOG | Utel","description":"Blog UTEL Universidad en L\u00ednea","publisher":{"@id":"https:\/\/utel.mx\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/utel.mx\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/utel.mx\/blog\/#organization","name":"BLOG | Utel","url":"https:\/\/utel.mx\/blog\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/utel.mx\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/utel.mx\/blog\/wp-content\/uploads\/2023\/03\/cropped-logo-blog.png","contentUrl":"https:\/\/utel.mx\/blog\/wp-content\/uploads\/2023\/03\/cropped-logo-blog.png","width":237,"height":64,"caption":"BLOG | Utel"},"image":{"@id":"https:\/\/utel.mx\/blog\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/utel.mx\/blog\/#\/schema\/person\/02ff4004657582a6dde2023933a23cea","name":"David Mora","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/utel.mx\/blog\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/a26766025e096bd4334bd54509ff15a6?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a26766025e096bd4334bd54509ff15a6?s=96&d=mm&r=g","caption":"David Mora"}}]}},"_links":{"self":[{"href":"https:\/\/utel.mx\/blog\/wp-json\/wp\/v2\/posts\/36417","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/utel.mx\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/utel.mx\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/utel.mx\/blog\/wp-json\/wp\/v2\/users\/82"}],"replies":[{"embeddable":true,"href":"https:\/\/utel.mx\/blog\/wp-json\/wp\/v2\/comments?post=36417"}],"version-history":[{"count":1,"href":"https:\/\/utel.mx\/blog\/wp-json\/wp\/v2\/posts\/36417\/revisions"}],"predecessor-version":[{"id":40129,"href":"https:\/\/utel.mx\/blog\/wp-json\/wp\/v2\/posts\/36417\/revisions\/40129"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/utel.mx\/blog\/wp-json\/wp\/v2\/media\/36418"}],"wp:attachment":[{"href":"https:\/\/utel.mx\/blog\/wp-json\/wp\/v2\/media?parent=36417"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/utel.mx\/blog\/wp-json\/wp\/v2\/categories?post=36417"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/utel.mx\/blog\/wp-json\/wp\/v2\/tags?post=36417"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}