{"id":36574,"date":"2021-02-26T14:45:29","date_gmt":"2021-02-26T14:45:29","guid":{"rendered":"http:\/\/utel.mx\/blog\/?p=36574"},"modified":"2023-03-10T17:13:32","modified_gmt":"2023-03-10T17:13:32","slug":"utel-presente-en-el-congreso-global-virtual-educa-lisboa","status":"publish","type":"post","link":"https:\/\/utel.mx\/blog\/vida-utel\/utel-presente-en-el-congreso-global-virtual-educa-lisboa\/","title":{"rendered":"UTEL presente en el Congreso global Virtual Educa Lisboa"},"content":{"rendered":"<h2><span style=\"color: #000000;\">Los pr\u00f3ximos d\u00edas 3, 4 y 5 de marzo se llevar\u00e1 a cabo el evento<\/span> <span style=\"color: #339966;\"><a style=\"color: #339966;\" href=\"https:\/\/virtualeduca.org\/congresoglobal\/\" target=\"_blank\" rel=\"noopener\"><strong>Virtual Educa Lisboa<\/strong><\/a><\/span><span style=\"color: #000000;\">, en donde la Universidad UTEL formar\u00e1 parte como\u00a0Sponsor Bronce\u00a0de este importante evento a nivel mundial.<\/span><\/h2>\n<p><span style=\"color: #000000;\">Virtual Educa es un renombrado\u00a0Congreso Global en el que participan docentes de diversas partes del mundo, haci\u00e9ndolo un encuentro entre todos involucrados en la Educaci\u00f3n y Formaci\u00f3n, ya sean gobiernos, academias, sectores corporativos y sociedad civil.<\/span><\/p>\n<p><span style=\"color: #000000;\">Los Encuentros internacionales Virtual Educa, que desde hace veinte a\u00f1os se llevan a cabo, son un referente a nivel mundial, lo que los convierte en <strong>Congresos globales<\/strong> de gran importancia.<\/span><\/p>\n<p><span style=\"color: #000000;\">En esta ocasi\u00f3n y con un formato online, Virtual Educa convoca a su evento anual, el cual se realizar\u00e1 desde su sede virtual. De esta manera, la Universidad UTEL refuerza su\u00a0 importante participaci\u00f3n, ya que cuenta con m\u00e1s de 10 a\u00f1os de experiencia brindando educaci\u00f3n en l\u00ednea, adem\u00e1s de un avance tecnol\u00f3gico sobresaliente por las aulas virtuales educativas que atienden las necesidades de los estudiantes, fomentando su autonom\u00eda y desarrollando conocimientos relevantes con aplicaciones inmediatas para su incursi\u00f3n al mundo laboral.<\/span><\/p>\n<p><span style=\"color: #000000;\">Se ofrecer\u00e1n presentaciones de todas las tem\u00e1ticas digitales fundamentales, las cuales son de gran valor en la actualidad, desde diversas perspectivas: educaci\u00f3n exponencial, tecnolog\u00edas emergentes (Al, Big Data, cloud, etc.), tecnolog\u00edas educativas, modelos de aprendizaje (flipped classroom, deep learning, ABP, etc.), Educaci\u00f3n 4.0 e iniciativas de impacto como Coding, STEAM, makers, gamificaci\u00f3n, entre otras. Igualmente, se analizar\u00e1 el tema de la Agenda 2030.<\/span><\/p>\n<p><span style=\"color: #000000;\">Tambi\u00e9n se abordar\u00e1n temas de gran importancia como el desarrollo profesional docente, la transformaci\u00f3n digital, las habilidades transversales, el emprendimiento y el talento, la inclusi\u00f3n, sostenibilidad y la ciudadan\u00eda digital, todas desde el punto de vista de la innovaci\u00f3n.<\/span><\/p>\n<p><span style=\"color: #000000;\">Este evento virtual contar\u00e1 con varios espacios de exposici\u00f3n interactivos con stands virtuales de las diversas organizaciones, instituciones y compa\u00f1\u00edas, que mostrar\u00e1n sus soluciones educativas y tecnolog\u00edas aplicadas a la educaci\u00f3n. Adem\u00e1s de esto, los asistentes podr\u00e1n aprovechar otros beneficios como:<\/span><\/p>\n<ul>\n<li><span style=\"color: #000000;\">Zona de networking en donde se podr\u00e1 contactar a los asistentes, ponentes y expositores en chats grupales o personales.<\/span><\/li>\n<li><span style=\"color: #000000;\">Auditorio principal en donde habr\u00e1 conferencias, presentaciones, paneles o mesas redondas con expertos<\/span><\/li>\n<li><span style=\"color: #000000;\">3 salas con sesiones simult\u00e1neas en donde habr\u00e1 programas en directo, semidirecto o pregrabado.<\/span><\/li>\n<li><span style=\"color: #000000;\">Aula Tech en donde habr\u00e1 presentaciones de tecnolog\u00edas de impacto, soluciones educativas y productos comerciales con patrocinadores y socios de Virtual Educa.<\/span><\/li>\n<\/ul>\n<p><span style=\"color: #000000;\">Como parte de este importante evento, el d\u00eda 4 de marzo, el Doctor Rafael Mart\u00ednez Campoblanco,\u00a0Director de Vinculaci\u00f3n Institucional de UTEL M\u00e9xico, presentar\u00e1 su ponencia \u201cLa experiencia del estudiante en la educaci\u00f3n online\u201d a las 9:40 hrs. (Tiempo de M\u00e9xico) como parte de UTEL M\u00e9xico. <\/span><\/p>\n<p><span style=\"color: #000000;\">De esta manera y gracias a que podemos contar m\u00e1s de 75,000\u00a0estudiantes y egresados\u00a0en el mundo, adem\u00e1s de 2,500 colaboradores y m\u00e1s de 900 docentes con amplia experiencia en educaci\u00f3n en l\u00ednea\u00a0es que nos sentimos orgullosos de formar parte de este extraordinario evento. As\u00ed, reforzamos nuestra misi\u00f3n de ser parte del logro de los objetivos estudiantiles para impulsar su calidad de vida con programas que van desde preparatoria hasta doctorado.<\/span><\/p>\n<p><span style=\"color: #000000;\">UTEL es la Universidad #1 en l\u00ednea y estar\u00e1 presente en Virtual Educa. \u00a1No te puedes perder su participaci\u00f3n este 4 de marzo!<\/span><\/p>\n<p><a href=\"https:\/\/virtualeduca.org\/congresoglobal\/\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" class=\" size-medium wp-image-35246 aligncenter\" src=\"http:\/\/utel.mx\/blog\/wp-content\/uploads\/2020\/10\/B1-300x39.png\" alt=\"Conoce m\u00e1s sobre UTEL\" width=\"300\" height=\"39\" srcset=\"https:\/\/utel.mx\/blog\/wp-content\/uploads\/2020\/10\/B1-300x39.png 300w, https:\/\/utel.mx\/blog\/wp-content\/uploads\/2020\/10\/B1-200x26.png 200w, https:\/\/utel.mx\/blog\/wp-content\/uploads\/2020\/10\/B1.png 408w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<div id=\"advads-551854903\" class=\"advads-cta-lp-banner-form advads-entity-placement\"><a href=\"https:\/\/utel.mx\/blog\/admisiones-universidad-online\/?utm_source=blog&#038;utm_medium=CTAlink&#038;utm_campaign=MKTseo\" aria-label=\"Universidad en linea\"><img src=\"https:\/\/utel.mx\/blog\/wp-content\/uploads\/2025\/04\/universidad-en-linea-1.png\" alt=\"Universidad en linea\"  srcset=\"https:\/\/utel.mx\/blog\/wp-content\/uploads\/2025\/04\/universidad-en-linea-1.png 626w, https:\/\/utel.mx\/blog\/wp-content\/uploads\/2025\/04\/universidad-en-linea-1-420x168.png 420w\" sizes=\"(max-width: 626px) 100vw, 626px\" width=\"626\" height=\"250\"   \/><\/a><\/div>","protected":false},"excerpt":{"rendered":"<p> [&hellip;]<\/p>\n","protected":false},"author":82,"featured_media":36576,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-gradient":""}},"footnotes":""},"categories":[3461,34],"tags":[],"class_list":["post-36574","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-business-school","category-vida-utel"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>UTEL presente en el Congreso global Virtual Educa Lisboa - BLOG | Utel<\/title>\n<meta name=\"description\" content=\"La Universidad UTEL participa en el evento global Virtual Educa Lisboa\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/utel.mx\/blog\/vida-utel\/utel-presente-en-el-congreso-global-virtual-educa-lisboa\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"UTEL presente en el Congreso global Virtual Educa Lisboa - BLOG | Utel\" \/>\n<meta property=\"og:description\" content=\"La Universidad UTEL participa en el evento global Virtual Educa Lisboa\" \/>\n<meta property=\"og:url\" content=\"https:\/\/utel.mx\/blog\/vida-utel\/utel-presente-en-el-congreso-global-virtual-educa-lisboa\/\" \/>\n<meta property=\"og:site_name\" content=\"BLOG | Utel\" \/>\n<meta property=\"article:published_time\" content=\"2021-02-26T14:45:29+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-03-10T17:13:32+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/utel.mx\/blog\/wp-content\/uploads\/2021\/02\/Headers_Feb21_25_2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"300\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"David Mora\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"David Mora\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/utel.mx\/blog\/vida-utel\/utel-presente-en-el-congreso-global-virtual-educa-lisboa\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/utel.mx\/blog\/vida-utel\/utel-presente-en-el-congreso-global-virtual-educa-lisboa\/\"},\"author\":{\"name\":\"David Mora\",\"@id\":\"https:\/\/utel.mx\/blog\/#\/schema\/person\/02ff4004657582a6dde2023933a23cea\"},\"headline\":\"UTEL presente en el Congreso global Virtual Educa Lisboa\",\"datePublished\":\"2021-02-26T14:45:29+00:00\",\"dateModified\":\"2023-03-10T17:13:32+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/utel.mx\/blog\/vida-utel\/utel-presente-en-el-congreso-global-virtual-educa-lisboa\/\"},\"wordCount\":584,\"publisher\":{\"@id\":\"https:\/\/utel.mx\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/utel.mx\/blog\/vida-utel\/utel-presente-en-el-congreso-global-virtual-educa-lisboa\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/utel.mx\/blog\/wp-content\/uploads\/2021\/02\/Headers_Feb21_25_2.jpg\",\"articleSection\":[\"Business School\",\"Vida Utel\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/utel.mx\/blog\/vida-utel\/utel-presente-en-el-congreso-global-virtual-educa-lisboa\/\",\"url\":\"https:\/\/utel.mx\/blog\/vida-utel\/utel-presente-en-el-congreso-global-virtual-educa-lisboa\/\",\"name\":\"UTEL presente en el Congreso global Virtual Educa Lisboa - BLOG | Utel\",\"isPartOf\":{\"@id\":\"https:\/\/utel.mx\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/utel.mx\/blog\/vida-utel\/utel-presente-en-el-congreso-global-virtual-educa-lisboa\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/utel.mx\/blog\/vida-utel\/utel-presente-en-el-congreso-global-virtual-educa-lisboa\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/utel.mx\/blog\/wp-content\/uploads\/2021\/02\/Headers_Feb21_25_2.jpg\",\"datePublished\":\"2021-02-26T14:45:29+00:00\",\"dateModified\":\"2023-03-10T17:13:32+00:00\",\"description\":\"La Universidad UTEL participa en el evento global Virtual Educa Lisboa\",\"breadcrumb\":{\"@id\":\"https:\/\/utel.mx\/blog\/vida-utel\/utel-presente-en-el-congreso-global-virtual-educa-lisboa\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/utel.mx\/blog\/vida-utel\/utel-presente-en-el-congreso-global-virtual-educa-lisboa\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/utel.mx\/blog\/vida-utel\/utel-presente-en-el-congreso-global-virtual-educa-lisboa\/#primaryimage\",\"url\":\"https:\/\/utel.mx\/blog\/wp-content\/uploads\/2021\/02\/Headers_Feb21_25_2.jpg\",\"contentUrl\":\"https:\/\/utel.mx\/blog\/wp-content\/uploads\/2021\/02\/Headers_Feb21_25_2.jpg\",\"width\":600,\"height\":300,\"caption\":\"UTEL presente en el Congreso global Virtual Educa Lisboa\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/utel.mx\/blog\/vida-utel\/utel-presente-en-el-congreso-global-virtual-educa-lisboa\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/utel.mx\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"UTEL presente en el Congreso global Virtual Educa Lisboa\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/utel.mx\/blog\/#website\",\"url\":\"https:\/\/utel.mx\/blog\/\",\"name\":\"BLOG | Utel\",\"description\":\"Blog UTEL Universidad en L\u00ednea\",\"publisher\":{\"@id\":\"https:\/\/utel.mx\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/utel.mx\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/utel.mx\/blog\/#organization\",\"name\":\"BLOG | Utel\",\"url\":\"https:\/\/utel.mx\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/utel.mx\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/utel.mx\/blog\/wp-content\/uploads\/2023\/03\/cropped-logo-blog.png\",\"contentUrl\":\"https:\/\/utel.mx\/blog\/wp-content\/uploads\/2023\/03\/cropped-logo-blog.png\",\"width\":237,\"height\":64,\"caption\":\"BLOG | Utel\"},\"image\":{\"@id\":\"https:\/\/utel.mx\/blog\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/utel.mx\/blog\/#\/schema\/person\/02ff4004657582a6dde2023933a23cea\",\"name\":\"David Mora\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/utel.mx\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/a26766025e096bd4334bd54509ff15a6?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/a26766025e096bd4334bd54509ff15a6?s=96&d=mm&r=g\",\"caption\":\"David Mora\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"UTEL presente en el Congreso global Virtual Educa Lisboa - BLOG | Utel","description":"La Universidad UTEL participa en el evento global Virtual Educa Lisboa","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/utel.mx\/blog\/vida-utel\/utel-presente-en-el-congreso-global-virtual-educa-lisboa\/","og_locale":"es_ES","og_type":"article","og_title":"UTEL presente en el Congreso global Virtual Educa Lisboa - BLOG | Utel","og_description":"La Universidad UTEL participa en el evento global Virtual Educa Lisboa","og_url":"https:\/\/utel.mx\/blog\/vida-utel\/utel-presente-en-el-congreso-global-virtual-educa-lisboa\/","og_site_name":"BLOG | Utel","article_published_time":"2021-02-26T14:45:29+00:00","article_modified_time":"2023-03-10T17:13:32+00:00","og_image":[{"width":600,"height":300,"url":"https:\/\/utel.mx\/blog\/wp-content\/uploads\/2021\/02\/Headers_Feb21_25_2.jpg","type":"image\/jpeg"}],"author":"David Mora","twitter_misc":{"Written by":"David Mora","Est. reading time":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/utel.mx\/blog\/vida-utel\/utel-presente-en-el-congreso-global-virtual-educa-lisboa\/#article","isPartOf":{"@id":"https:\/\/utel.mx\/blog\/vida-utel\/utel-presente-en-el-congreso-global-virtual-educa-lisboa\/"},"author":{"name":"David Mora","@id":"https:\/\/utel.mx\/blog\/#\/schema\/person\/02ff4004657582a6dde2023933a23cea"},"headline":"UTEL presente en el Congreso global Virtual Educa Lisboa","datePublished":"2021-02-26T14:45:29+00:00","dateModified":"2023-03-10T17:13:32+00:00","mainEntityOfPage":{"@id":"https:\/\/utel.mx\/blog\/vida-utel\/utel-presente-en-el-congreso-global-virtual-educa-lisboa\/"},"wordCount":584,"publisher":{"@id":"https:\/\/utel.mx\/blog\/#organization"},"image":{"@id":"https:\/\/utel.mx\/blog\/vida-utel\/utel-presente-en-el-congreso-global-virtual-educa-lisboa\/#primaryimage"},"thumbnailUrl":"https:\/\/utel.mx\/blog\/wp-content\/uploads\/2021\/02\/Headers_Feb21_25_2.jpg","articleSection":["Business School","Vida Utel"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/utel.mx\/blog\/vida-utel\/utel-presente-en-el-congreso-global-virtual-educa-lisboa\/","url":"https:\/\/utel.mx\/blog\/vida-utel\/utel-presente-en-el-congreso-global-virtual-educa-lisboa\/","name":"UTEL presente en el Congreso global Virtual Educa Lisboa - BLOG | Utel","isPartOf":{"@id":"https:\/\/utel.mx\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/utel.mx\/blog\/vida-utel\/utel-presente-en-el-congreso-global-virtual-educa-lisboa\/#primaryimage"},"image":{"@id":"https:\/\/utel.mx\/blog\/vida-utel\/utel-presente-en-el-congreso-global-virtual-educa-lisboa\/#primaryimage"},"thumbnailUrl":"https:\/\/utel.mx\/blog\/wp-content\/uploads\/2021\/02\/Headers_Feb21_25_2.jpg","datePublished":"2021-02-26T14:45:29+00:00","dateModified":"2023-03-10T17:13:32+00:00","description":"La Universidad UTEL participa en el evento global Virtual Educa Lisboa","breadcrumb":{"@id":"https:\/\/utel.mx\/blog\/vida-utel\/utel-presente-en-el-congreso-global-virtual-educa-lisboa\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/utel.mx\/blog\/vida-utel\/utel-presente-en-el-congreso-global-virtual-educa-lisboa\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/utel.mx\/blog\/vida-utel\/utel-presente-en-el-congreso-global-virtual-educa-lisboa\/#primaryimage","url":"https:\/\/utel.mx\/blog\/wp-content\/uploads\/2021\/02\/Headers_Feb21_25_2.jpg","contentUrl":"https:\/\/utel.mx\/blog\/wp-content\/uploads\/2021\/02\/Headers_Feb21_25_2.jpg","width":600,"height":300,"caption":"UTEL presente en el Congreso global Virtual Educa Lisboa"},{"@type":"BreadcrumbList","@id":"https:\/\/utel.mx\/blog\/vida-utel\/utel-presente-en-el-congreso-global-virtual-educa-lisboa\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/utel.mx\/blog\/"},{"@type":"ListItem","position":2,"name":"UTEL presente en el Congreso global Virtual Educa Lisboa"}]},{"@type":"WebSite","@id":"https:\/\/utel.mx\/blog\/#website","url":"https:\/\/utel.mx\/blog\/","name":"BLOG | Utel","description":"Blog UTEL Universidad en L\u00ednea","publisher":{"@id":"https:\/\/utel.mx\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/utel.mx\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/utel.mx\/blog\/#organization","name":"BLOG | Utel","url":"https:\/\/utel.mx\/blog\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/utel.mx\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/utel.mx\/blog\/wp-content\/uploads\/2023\/03\/cropped-logo-blog.png","contentUrl":"https:\/\/utel.mx\/blog\/wp-content\/uploads\/2023\/03\/cropped-logo-blog.png","width":237,"height":64,"caption":"BLOG | Utel"},"image":{"@id":"https:\/\/utel.mx\/blog\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/utel.mx\/blog\/#\/schema\/person\/02ff4004657582a6dde2023933a23cea","name":"David Mora","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/utel.mx\/blog\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/a26766025e096bd4334bd54509ff15a6?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a26766025e096bd4334bd54509ff15a6?s=96&d=mm&r=g","caption":"David Mora"}}]}},"_links":{"self":[{"href":"https:\/\/utel.mx\/blog\/wp-json\/wp\/v2\/posts\/36574","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/utel.mx\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/utel.mx\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/utel.mx\/blog\/wp-json\/wp\/v2\/users\/82"}],"replies":[{"embeddable":true,"href":"https:\/\/utel.mx\/blog\/wp-json\/wp\/v2\/comments?post=36574"}],"version-history":[{"count":1,"href":"https:\/\/utel.mx\/blog\/wp-json\/wp\/v2\/posts\/36574\/revisions"}],"predecessor-version":[{"id":46510,"href":"https:\/\/utel.mx\/blog\/wp-json\/wp\/v2\/posts\/36574\/revisions\/46510"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/utel.mx\/blog\/wp-json\/wp\/v2\/media\/36576"}],"wp:attachment":[{"href":"https:\/\/utel.mx\/blog\/wp-json\/wp\/v2\/media?parent=36574"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/utel.mx\/blog\/wp-json\/wp\/v2\/categories?post=36574"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/utel.mx\/blog\/wp-json\/wp\/v2\/tags?post=36574"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}