{"id":37264,"date":"2021-06-10T17:15:31","date_gmt":"2021-06-10T17:15:31","guid":{"rendered":"http:\/\/utel.mx\/blog\/?p=37264"},"modified":"2023-03-10T17:13:06","modified_gmt":"2023-03-10T17:13:06","slug":"en-que-trabaja-un-politologo","status":"publish","type":"post","link":"https:\/\/utel.mx\/blog\/estudia-en-linea\/en-que-trabaja-un-politologo\/","title":{"rendered":"\u00bfEn qu\u00e9 trabaja un polit\u00f3logo?"},"content":{"rendered":"<p><span style=\"color: #000000;\">Analizar la Ciencia Pol\u00edtica es una labor interesante, adem\u00e1s de su objeto de estudio, or\u00edgenes y evoluci\u00f3n, pero \u00bfqui\u00e9n se encarga de esto? y sobre todo \u00bfC\u00f3mo se le conoce al profesional que estudia Ciencias Pol\u00edticas? La persona que estudia esta disciplina es llamada polit\u00f3logo, \u00e9l es el especialista y estudioso del \u00e1rea. Pero \u00bfqu\u00e9 sabemos de un polit\u00f3logo? A continuaci\u00f3n revisaremos qu\u00e9 estudia, cu\u00e1les son los conocimientos, las habilidades que desarrolla y en qu\u00e9 trabaja esta persona.<\/span><\/p>\n<h2><span style=\"color: #000000;\">\u00bfQu\u00e9 es un polit\u00f3logo?<\/span><\/h2>\n<p><span style=\"color: #000000;\">Un polit\u00f3logo es un experto en la ciencia que se dedica al estudio de la pol\u00edtica, el dise\u00f1o y la ejecuci\u00f3n de acciones p\u00fablicas para la organizaci\u00f3n de la sociedad. Por lo tanto, este perfil profesional tendr\u00e1 como objetivo analizar las relaciones de poder que se establecen entre los ciudadanos, las caracter\u00edsticas de las instituciones, los procesos de elecciones y las formas de acceso al gobierno, la detecci\u00f3n de aciertos, fallas, necesidades y otros puntos clave del contexto pol\u00edtico. (Concepto de, 2020).<\/span><\/p>\n<p><span style=\"color: #000000;\">Un profesional de la Ciencia Pol\u00edtica se prepara para ser capaz de entender y explicar las problem\u00e1ticas pol\u00edticas que enfrenta cualquier sociedad, para esto debe tener un enfoque multidisciplinario, el cual le dar\u00e1 las herramientas necesarias para lograr un entendimiento integral. Algunas de las \u00e1reas del conocimiento que integra un polit\u00f3logo en su formaci\u00f3n son sociolog\u00eda, econom\u00eda, historia y estad\u00edstica, entre otras. (Concepto de, 2020).<\/span><\/p>\n<h2><span style=\"color: #000000;\">\u00bfQu\u00e9 caracter\u00edsticas tiene un profesional de la politolog\u00eda?<\/span><\/h2>\n<p><span style=\"color: #000000;\">Antes de revisar en qu\u00e9 trabaja un polit\u00f3logo, nos gustar\u00eda recalcar algunas competencias y habilidades importantes que debe desarrollar este profesional.<\/span><\/p>\n<ul>\n<li><span style=\"color: #000000;\">Es importante que un polit\u00f3logo tenga pensamiento cr\u00edtico; es decir, adquirir la capacidad de relacionar conceptos, realizar conclusiones y razonamientos pertinentes.<\/span><\/li>\n<li><span style=\"color: #000000;\">Es relevante tambi\u00e9n que desarrolle la capacidad de investigar, que pueda recopilar informaci\u00f3n y hacer investigaciones exhaustivas.<\/span><\/li>\n<li><span style=\"color: #000000;\">Parte de su rol como polit\u00f3logo es estar informado tanto de la historia como de la actualidad para as\u00ed poder generar an\u00e1lisis efectivos con respecto a la situaci\u00f3n pol\u00edtica en la sociedad.<\/span><\/li>\n<li><span style=\"color: #000000;\">El tener una visi\u00f3n global le permitir\u00e1 afrontar de mejor manera los retos de esta disciplina, para lograrlo deber\u00e1 desarrollar conocimientos en diferentes \u00e1mbitos, tales como administraci\u00f3n p\u00fablica, relaciones internacionales o filosof\u00eda, entre otras<\/span><\/li>\n<\/ul>\n<h2><span style=\"color: #000000;\">Campo profesional del polit\u00f3logo<\/span><\/h2>\n<p><span style=\"color: #000000;\">Un polit\u00f3logo puede trabajar tanto en el sector p\u00fablico como en el privado, si decide desempe\u00f1arse en el sector p\u00fablico puede realizar actividades relacionadas al asesoramiento y dise\u00f1o de diferentes pol\u00edticas p\u00fablicas para el Gobierno y partidos pol\u00edticos. Tambi\u00e9n se puede desempe\u00f1ar como funcionario p\u00fablico o asesor del poder legislativo y ejecutivo en las diferentes administraciones del Estado. En el caso que se decida por el sector privado puede desempe\u00f1arse como consultor, en el \u00e1rea de educaci\u00f3n, en medios de comunicaci\u00f3n o en relaciones internacionales. (Trabajar por el mundo org, 2020).<\/span><\/p>\n<p><span style=\"color: #000000;\">Si quieres conocer m\u00e1s acerca de la carrera de Ciencias Pol\u00edticas y Administraci\u00f3n P\u00fablica en UTEL te invitamos a ver la ficha t\u00e9cnica de este programa en nuestro sitio web. <\/span><\/p>\n<p><a href=\"https:\/\/chile.utel.edu.mx\/licenciatura-en-ciencias-politicas\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" class=\" size-full wp-image-18233 aligncenter\" src=\"http:\/\/utel.mx\/blog\/wp-content\/uploads\/2015\/05\/boton_blog.png\" alt=\"Bot\u00f3n contacto\" width=\"232\" height=\"71\" \/><\/a><\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><span style=\"color: #000000;\"><strong>Mar\u00eda Jos\u00e9 Ram\u00edrez D.<\/strong><\/span><\/p>\n<p><span style=\"color: #000000;\"><strong>Equipo de Branding &amp; PR UTEL <\/strong><\/span><\/p>\n<h3><span style=\"color: #000000;\">Referencias<\/span><\/h3>\n<p><span style=\"color: #000000;\"><em>Concepto.de<\/em>. (31 mayo, 2020). Obtenido de<\/span> <span style=\"color: #339966;\">https:\/\/concepto.de\/politologo\/<\/span><\/p>\n<p><span style=\"color: #000000;\"><em>Trabajar por el mundo org<\/em>. (11 de 2020). Obtenido de<\/span> <span style=\"color: #339966;\">https:\/\/trabajarporelmundo.org\/guia-para-trabajar-como-politologo\/<\/span><\/p>\n<p>&nbsp;<\/p>\n<div id=\"advads-1395157095\" class=\"advads-cta-lp-banner-form advads-entity-placement\"><a href=\"https:\/\/utel.mx\/blog\/admisiones-universidad-online\/?utm_source=blog&#038;utm_medium=CTAlink&#038;utm_campaign=MKTseo\" aria-label=\"Universidad en linea\"><img src=\"https:\/\/utel.mx\/blog\/wp-content\/uploads\/2025\/04\/universidad-en-linea-1.png\" alt=\"Universidad en linea\"  srcset=\"https:\/\/utel.mx\/blog\/wp-content\/uploads\/2025\/04\/universidad-en-linea-1.png 626w, https:\/\/utel.mx\/blog\/wp-content\/uploads\/2025\/04\/universidad-en-linea-1-420x168.png 420w\" sizes=\"(max-width: 626px) 100vw, 626px\" width=\"626\" height=\"250\"   \/><\/a><\/div>","protected":false},"excerpt":{"rendered":"<p> [&hellip;]<\/p>\n","protected":false},"author":82,"featured_media":37266,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-gradient":""}},"footnotes":""},"categories":[3462,7],"tags":[],"class_list":["post-37264","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-school-of-education","category-estudia-en-linea"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u00bfEn qu\u00e9 trabaja un polit\u00f3logo? - BLOG | Utel<\/title>\n<meta name=\"description\" content=\"Conoce m\u00e1s acerca de la labor de un polit\u00f3logo, cu\u00e1les son sus conocimientos y habilidades para llevar a cabo su profesi\u00f3n.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/utel.mx\/blog\/estudia-en-linea\/en-que-trabaja-un-politologo\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00bfEn qu\u00e9 trabaja un polit\u00f3logo? - BLOG | Utel\" \/>\n<meta property=\"og:description\" content=\"Conoce m\u00e1s acerca de la labor de un polit\u00f3logo, cu\u00e1les son sus conocimientos y habilidades para llevar a cabo su profesi\u00f3n.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/utel.mx\/blog\/estudia-en-linea\/en-que-trabaja-un-politologo\/\" \/>\n<meta property=\"og:site_name\" content=\"BLOG | Utel\" \/>\n<meta property=\"article:published_time\" content=\"2021-06-10T17:15:31+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-03-10T17:13:06+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/utel.mx\/blog\/wp-content\/uploads\/2021\/06\/Header_Junio21_09_4.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"300\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"David Mora\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"David Mora\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/utel.mx\/blog\/estudia-en-linea\/en-que-trabaja-un-politologo\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/utel.mx\/blog\/estudia-en-linea\/en-que-trabaja-un-politologo\/\"},\"author\":{\"name\":\"David Mora\",\"@id\":\"https:\/\/utel.mx\/blog\/#\/schema\/person\/02ff4004657582a6dde2023933a23cea\"},\"headline\":\"\u00bfEn qu\u00e9 trabaja un polit\u00f3logo?\",\"datePublished\":\"2021-06-10T17:15:31+00:00\",\"dateModified\":\"2023-03-10T17:13:06+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/utel.mx\/blog\/estudia-en-linea\/en-que-trabaja-un-politologo\/\"},\"wordCount\":590,\"publisher\":{\"@id\":\"https:\/\/utel.mx\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/utel.mx\/blog\/estudia-en-linea\/en-que-trabaja-un-politologo\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/utel.mx\/blog\/wp-content\/uploads\/2021\/06\/Header_Junio21_09_4.jpg\",\"articleSection\":[\"Educaci\u00f3n\",\"Estudia en L\u00ednea\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/utel.mx\/blog\/estudia-en-linea\/en-que-trabaja-un-politologo\/\",\"url\":\"https:\/\/utel.mx\/blog\/estudia-en-linea\/en-que-trabaja-un-politologo\/\",\"name\":\"\u00bfEn qu\u00e9 trabaja un polit\u00f3logo? - BLOG | Utel\",\"isPartOf\":{\"@id\":\"https:\/\/utel.mx\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/utel.mx\/blog\/estudia-en-linea\/en-que-trabaja-un-politologo\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/utel.mx\/blog\/estudia-en-linea\/en-que-trabaja-un-politologo\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/utel.mx\/blog\/wp-content\/uploads\/2021\/06\/Header_Junio21_09_4.jpg\",\"datePublished\":\"2021-06-10T17:15:31+00:00\",\"dateModified\":\"2023-03-10T17:13:06+00:00\",\"description\":\"Conoce m\u00e1s acerca de la labor de un polit\u00f3logo, cu\u00e1les son sus conocimientos y habilidades para llevar a cabo su profesi\u00f3n.\",\"breadcrumb\":{\"@id\":\"https:\/\/utel.mx\/blog\/estudia-en-linea\/en-que-trabaja-un-politologo\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/utel.mx\/blog\/estudia-en-linea\/en-que-trabaja-un-politologo\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/utel.mx\/blog\/estudia-en-linea\/en-que-trabaja-un-politologo\/#primaryimage\",\"url\":\"https:\/\/utel.mx\/blog\/wp-content\/uploads\/2021\/06\/Header_Junio21_09_4.jpg\",\"contentUrl\":\"https:\/\/utel.mx\/blog\/wp-content\/uploads\/2021\/06\/Header_Junio21_09_4.jpg\",\"width\":600,\"height\":300,\"caption\":\"Polit\u00f3logo\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/utel.mx\/blog\/estudia-en-linea\/en-que-trabaja-un-politologo\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/utel.mx\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00bfEn qu\u00e9 trabaja un polit\u00f3logo?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/utel.mx\/blog\/#website\",\"url\":\"https:\/\/utel.mx\/blog\/\",\"name\":\"BLOG | Utel\",\"description\":\"Blog UTEL Universidad en L\u00ednea\",\"publisher\":{\"@id\":\"https:\/\/utel.mx\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/utel.mx\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/utel.mx\/blog\/#organization\",\"name\":\"BLOG | Utel\",\"url\":\"https:\/\/utel.mx\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/utel.mx\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/utel.mx\/blog\/wp-content\/uploads\/2023\/03\/cropped-logo-blog.png\",\"contentUrl\":\"https:\/\/utel.mx\/blog\/wp-content\/uploads\/2023\/03\/cropped-logo-blog.png\",\"width\":237,\"height\":64,\"caption\":\"BLOG | Utel\"},\"image\":{\"@id\":\"https:\/\/utel.mx\/blog\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/utel.mx\/blog\/#\/schema\/person\/02ff4004657582a6dde2023933a23cea\",\"name\":\"David Mora\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/utel.mx\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/a26766025e096bd4334bd54509ff15a6?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/a26766025e096bd4334bd54509ff15a6?s=96&d=mm&r=g\",\"caption\":\"David Mora\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00bfEn qu\u00e9 trabaja un polit\u00f3logo? - BLOG | Utel","description":"Conoce m\u00e1s acerca de la labor de un polit\u00f3logo, cu\u00e1les son sus conocimientos y habilidades para llevar a cabo su profesi\u00f3n.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/utel.mx\/blog\/estudia-en-linea\/en-que-trabaja-un-politologo\/","og_locale":"es_ES","og_type":"article","og_title":"\u00bfEn qu\u00e9 trabaja un polit\u00f3logo? - BLOG | Utel","og_description":"Conoce m\u00e1s acerca de la labor de un polit\u00f3logo, cu\u00e1les son sus conocimientos y habilidades para llevar a cabo su profesi\u00f3n.","og_url":"https:\/\/utel.mx\/blog\/estudia-en-linea\/en-que-trabaja-un-politologo\/","og_site_name":"BLOG | Utel","article_published_time":"2021-06-10T17:15:31+00:00","article_modified_time":"2023-03-10T17:13:06+00:00","og_image":[{"width":600,"height":300,"url":"https:\/\/utel.mx\/blog\/wp-content\/uploads\/2021\/06\/Header_Junio21_09_4.jpg","type":"image\/jpeg"}],"author":"David Mora","twitter_misc":{"Written by":"David Mora","Est. reading time":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/utel.mx\/blog\/estudia-en-linea\/en-que-trabaja-un-politologo\/#article","isPartOf":{"@id":"https:\/\/utel.mx\/blog\/estudia-en-linea\/en-que-trabaja-un-politologo\/"},"author":{"name":"David Mora","@id":"https:\/\/utel.mx\/blog\/#\/schema\/person\/02ff4004657582a6dde2023933a23cea"},"headline":"\u00bfEn qu\u00e9 trabaja un polit\u00f3logo?","datePublished":"2021-06-10T17:15:31+00:00","dateModified":"2023-03-10T17:13:06+00:00","mainEntityOfPage":{"@id":"https:\/\/utel.mx\/blog\/estudia-en-linea\/en-que-trabaja-un-politologo\/"},"wordCount":590,"publisher":{"@id":"https:\/\/utel.mx\/blog\/#organization"},"image":{"@id":"https:\/\/utel.mx\/blog\/estudia-en-linea\/en-que-trabaja-un-politologo\/#primaryimage"},"thumbnailUrl":"https:\/\/utel.mx\/blog\/wp-content\/uploads\/2021\/06\/Header_Junio21_09_4.jpg","articleSection":["Educaci\u00f3n","Estudia en L\u00ednea"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/utel.mx\/blog\/estudia-en-linea\/en-que-trabaja-un-politologo\/","url":"https:\/\/utel.mx\/blog\/estudia-en-linea\/en-que-trabaja-un-politologo\/","name":"\u00bfEn qu\u00e9 trabaja un polit\u00f3logo? - BLOG | Utel","isPartOf":{"@id":"https:\/\/utel.mx\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/utel.mx\/blog\/estudia-en-linea\/en-que-trabaja-un-politologo\/#primaryimage"},"image":{"@id":"https:\/\/utel.mx\/blog\/estudia-en-linea\/en-que-trabaja-un-politologo\/#primaryimage"},"thumbnailUrl":"https:\/\/utel.mx\/blog\/wp-content\/uploads\/2021\/06\/Header_Junio21_09_4.jpg","datePublished":"2021-06-10T17:15:31+00:00","dateModified":"2023-03-10T17:13:06+00:00","description":"Conoce m\u00e1s acerca de la labor de un polit\u00f3logo, cu\u00e1les son sus conocimientos y habilidades para llevar a cabo su profesi\u00f3n.","breadcrumb":{"@id":"https:\/\/utel.mx\/blog\/estudia-en-linea\/en-que-trabaja-un-politologo\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/utel.mx\/blog\/estudia-en-linea\/en-que-trabaja-un-politologo\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/utel.mx\/blog\/estudia-en-linea\/en-que-trabaja-un-politologo\/#primaryimage","url":"https:\/\/utel.mx\/blog\/wp-content\/uploads\/2021\/06\/Header_Junio21_09_4.jpg","contentUrl":"https:\/\/utel.mx\/blog\/wp-content\/uploads\/2021\/06\/Header_Junio21_09_4.jpg","width":600,"height":300,"caption":"Polit\u00f3logo"},{"@type":"BreadcrumbList","@id":"https:\/\/utel.mx\/blog\/estudia-en-linea\/en-que-trabaja-un-politologo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/utel.mx\/blog\/"},{"@type":"ListItem","position":2,"name":"\u00bfEn qu\u00e9 trabaja un polit\u00f3logo?"}]},{"@type":"WebSite","@id":"https:\/\/utel.mx\/blog\/#website","url":"https:\/\/utel.mx\/blog\/","name":"BLOG | Utel","description":"Blog UTEL Universidad en L\u00ednea","publisher":{"@id":"https:\/\/utel.mx\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/utel.mx\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/utel.mx\/blog\/#organization","name":"BLOG | Utel","url":"https:\/\/utel.mx\/blog\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/utel.mx\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/utel.mx\/blog\/wp-content\/uploads\/2023\/03\/cropped-logo-blog.png","contentUrl":"https:\/\/utel.mx\/blog\/wp-content\/uploads\/2023\/03\/cropped-logo-blog.png","width":237,"height":64,"caption":"BLOG | Utel"},"image":{"@id":"https:\/\/utel.mx\/blog\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/utel.mx\/blog\/#\/schema\/person\/02ff4004657582a6dde2023933a23cea","name":"David Mora","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/utel.mx\/blog\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/a26766025e096bd4334bd54509ff15a6?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a26766025e096bd4334bd54509ff15a6?s=96&d=mm&r=g","caption":"David Mora"}}]}},"_links":{"self":[{"href":"https:\/\/utel.mx\/blog\/wp-json\/wp\/v2\/posts\/37264","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/utel.mx\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/utel.mx\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/utel.mx\/blog\/wp-json\/wp\/v2\/users\/82"}],"replies":[{"embeddable":true,"href":"https:\/\/utel.mx\/blog\/wp-json\/wp\/v2\/comments?post=37264"}],"version-history":[{"count":1,"href":"https:\/\/utel.mx\/blog\/wp-json\/wp\/v2\/posts\/37264\/revisions"}],"predecessor-version":[{"id":46443,"href":"https:\/\/utel.mx\/blog\/wp-json\/wp\/v2\/posts\/37264\/revisions\/46443"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/utel.mx\/blog\/wp-json\/wp\/v2\/media\/37266"}],"wp:attachment":[{"href":"https:\/\/utel.mx\/blog\/wp-json\/wp\/v2\/media?parent=37264"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/utel.mx\/blog\/wp-json\/wp\/v2\/categories?post=37264"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/utel.mx\/blog\/wp-json\/wp\/v2\/tags?post=37264"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}